{"id":134541,"date":"2021-05-20T16:47:57","date_gmt":"2021-05-20T14:47:57","guid":{"rendered":"https:\/\/www.shavei.org\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/"},"modified":"2021-05-20T16:47:57","modified_gmt":"2021-05-20T14:47:57","slug":"fundamentalmente-freund-no-dejen-morir-el-ladino","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/","title":{"rendered":"Fundamentalmente Freund: No dejen morir el Ladino"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Si lo pensamos racionalmente, el legado de la juder?a medieval\nespa?ola ya deber?a haber desaparecido hace mucho. Esa comunidad, la m?s grande\ny m?s influyente de Europa en esa ?poca, fue expulsada en 1942 y se dispers?\ncomo el viento, reparti?ndose por las zonas del Oriente Medio, los Balcanes y\nel Norte de ?frica. Pocas culturas podr?an tener esperanza de sobrevivir a un\ntrauma colectivo tan catastr?fico, estando sus miembros obligados a reconstruir\nsus vidas en tierras extranjeras.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No obstante, y contra todas las probabilidades, las tradiciones\nculturales, ling??sticas y religiosas ?nicas de los jud?os espa?oles siguen\nvivas, e Israel y el pueblo jud?o deber?an hacer m?s para proteger y\ndesarrollar esta parte tan importante del patrimonio de nuestro pueblo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pude vislumbrar un poco de este valioso legado en el <em>seder <\/em>de\neste a?o, cuando me reun? con mi nuera y su familia, parte de la cual son\njud?os de origen jud?o-turca, para celebrar el relato anual del ?xodo de\nEgipto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">S?bitamente, casi sin aviso, me vi expuesto a nuevas canciones,\ndiferentes melod?as e incluso partes de la lectura en ladino, o jud?o-espa?ol,\nun dialecto emotivo donde se mezclan palabras en espa?ol antiguo, hebreo y\narameo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Yo crec? con las costumbres y melod?as asquenaz?es habituales, y por\neso fue enriquecedor poder conocer otras tradiciones jud?as, vividas\norgullosamente, y tan autenticas y leg?timas como las nuestras. Con un poco de\nfantas?a, pod?a incluso imaginar un grupo de jud?os espa?oles exiliados\nsentados alrededor de la mesa del <em>seder <\/em>en Izmir, N?poles o Sarajevo en\nlos siglos XVI o XVII<em>, <\/em>entonando algunas de las mismas melod?as. La\nhistoria del Ladino refleja de muchas maneras la historia de los ?ltimos seis\nsiglos del pueblo jud?o, que sobrevivi? a la expulsi?n, a la asimilaci?n y al\ngenocidio.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tal como el ?dish, la lengua franca de muchos jud?os asquenaz?es a\nlo largo de muchas generaciones, el Ladino sirvi? como tela cultural, una tela\nutilizada por muchos jud?os sefard?es para componer poes?a, disertar sobre la\nTor? y debatir cuestiones de importancia cultural y m?stica, bien como para\ndivulgar investigaciones en los dominios de la Historia, de las Matem?ticas o\nde la Astronom?a.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La obra m?s conocida escrita en ladino es quiz? el Meam Loez, un\ncomentario sobre la Biblia que combina exposiciones talmudicas, <em>midrashicas <\/em>y\n<em>halacjicas, <\/em>iniciado por el rabino Yaakov Culi en 1730 en Constantinopla\ny continuada por otros despu?s de su muerte. La obra, que est? traducida al\nhebreo y al ingl?s [y tambi?n al espa?ol], ha ganado cada vez m?s popularidad,\ntanto entre sefard?es como entre asquenaz?es.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Durante centenas de a?os, hasta el Holocausto, el ladino era el\nprimer idioma de muchos jud?os sefard?es en la regi?n del Mediterr?neo. Pero el\nasesinato de grandes n?meros de jud?os hablantes de ladino, en lugares como\nGrecia y Bosnia, por parte de los alemanes y sus c?mplices en la ?poca de la 2?\nGuerra Mundial, puso en peligro el bien-estar y el futuro de este idioma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las estad?sticas sobre el n?mero de hablantes de ladino que existen\nen el mundo hoy en d?a var?an entre solamente decenas de miles hasta doscientas\nmil. Pero como coment? la <em>NBC News<\/em> hace dos meses en un reportaje, ?Lo\nque es indiscutible es que la mayor parte de los hablantes nativos de ladino\nson personas mayores, y la mayor parte de sus hijos crecieron hablando otro\nidioma?. Por otras palabras, la riqueza de este idioma y cultura estar?n peligro\nde extinci?n si no se emplean grandes esfuerzos para preservarla.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Felizmente, se est?n poniendo en pr?ctica algunas medidas para\nimpedir que eso ocurra. Este a?o, por la segunda vez, tuvo lugar en el Centro\nde Historia Jud?a, en Nueva York, el D?a Internacional del Ladino, un d?a anual\norganizado por la Federaci?n Sefard? Americana y otras entidades, que incluye\nun festival dedicado a la m?sica y cultura ladinas. Tambi?n hubo eventos\nsimilares en otras ciudades.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El Ministerio de Cultura Israel? tiene la Autoridad Nacional para la\nCultura Ladina, establecida por el <em>knesset <\/em>[parlamento israel?] en 1996,\nque otorga becas para alentar los estudiantes a aprender el idioma, subvenciona\ntraducciones y produce libros y Cd&#8217;s con\ncuentos y canciones en ladino.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Algunos expertos, como el Dr. Eliezer Papo, de la Universidad de Ben Gurion,\ny el Prof. David Blunis, que lidera el programa de estudios ladinos en la\nUniversidad Hebraica de Jerusal?n, han estado trabajando hace a?os para\naumentar el conocimiento del p?blico general sobre el ladino, dando cursos y\nescribiendo art?culos y libros.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">?Y los alumnos m?s valientes pueden incluso encontrar videos con\nclases para aprender ladino en YouTube!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Pero, por varias razones, este idioma no ha logrado la atenci?n\nmerecida, y recibe menos recursos y fondos que otros programas similares que\ntienen como objetivo revivir el ?dish. Es llegado el momento de cambiar esto, y\nde que la cultura y tradiciones sefard?es y ladinas sean rescatadas y\nfortalecidas con la misma pasi?n involucrada en la preservaci?n del patrimonio\ncultural asquenazi.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las organizaciones jud?as norte-americanas, en conjunto con el\ngobierno israel?, deber?an hacer m?s para mantener el ladino y su cultura vivos\ny de buena salud ? porque el ladino y todo lo que el incluye son parte\nintegrante del largo y sinuoso pasaje de nuestro pueblo por el escenario de la\nHistoria. Permitir que ?l desaparezca o se transforme en un f?sil seria un\nafrontamiento a la historia jud?a y una p?rdida cultural irremplazable.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hace m?s de siete d?cadas, los nazis golpearon el Ladino y su cultura de un modo casi mortal. A trav?s de la indiferencia y de la apat?a, corremos el riesgo de que el golpe se vuelva fatal, lo que no podemos permitir que ocurra.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si lo pensamos racionalmente, el legado de la juder?a medieval espa?ola ya deber?a haber desaparecido hace mucho. Esa comunidad, la m?s grande y m?s influyente de Europa en esa ?poca, fue expulsada en 1942 y se dispers? como el viento, reparti?ndose por las zonas del&#8230;<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[5152,5153],"tags":[5154],"class_list":["post-134541","post","type-post","status-publish","format-standard","hentry","category-fundamentalmente-freundbnei-anusim","category-ladino-fundamentalmente-freundbnei-anusim","tag-bnei-anusimfundamentalmente-freundladinomichael-freund"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fundamentalmente Freund: No dejen morir el Ladino - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fundamentalmente Freund: No dejen morir el Ladino - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"Si lo pensamos racionalmente, el legado de la juder?a medieval espa?ola ya deber?a haber desaparecido hace mucho. Esa comunidad, la m?s grande y m?s influyente de Europa en esa ?poca, fue expulsada en 1942 y se dispers? como el viento, reparti?ndose por las zonas del...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-20T14:47:57+00:00\" \/>\n<meta name=\"author\" content=\"daniella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/\"},\"author\":{\"name\":\"daniella\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/628be1364b127546c700d93458cf9e4c\"},\"headline\":\"Fundamentalmente Freund: No dejen morir el Ladino\",\"datePublished\":\"2021-05-20T14:47:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/\"},\"wordCount\":1033,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"keywords\":[\"Bnei Anusim|Fundamentalmente Freund|Ladino|Michael Freund\"],\"articleSection\":[\"FUNDAMENTALMENTE FREUND|BNEI ANUSIM\",\"Ladino\"],\"inLanguage\":\"sp\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/\",\"name\":\"Fundamentalmente Freund: No dejen morir el Ladino - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"datePublished\":\"2021-05-20T14:47:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/#breadcrumb\"},\"inLanguage\":\"sp\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/fundamentalmente-freund-no-dejen-morir-el-ladino\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fundamentalmente Freund: No dejen morir el Ladino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sp\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sp\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/628be1364b127546c700d93458cf9e4c\",\"name\":\"daniella\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sp\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"caption\":\"daniella\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/author\\\/daniella\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fundamentalmente Freund: No dejen morir el Ladino - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/","og_locale":"en_US","og_type":"article","og_title":"Fundamentalmente Freund: No dejen morir el Ladino - Shavei Israel","og_description":"Si lo pensamos racionalmente, el legado de la juder?a medieval espa?ola ya deber?a haber desaparecido hace mucho. Esa comunidad, la m?s grande y m?s influyente de Europa en esa ?poca, fue expulsada en 1942 y se dispers? como el viento, reparti?ndose por las zonas del...","og_url":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/","og_site_name":"Shavei Israel","article_published_time":"2021-05-20T14:47:57+00:00","author":"daniella","twitter_card":"summary_large_image","twitter_misc":{"Written by":false,"Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/"},"author":{"name":"daniella","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/628be1364b127546c700d93458cf9e4c"},"headline":"Fundamentalmente Freund: No dejen morir el Ladino","datePublished":"2021-05-20T14:47:57+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/"},"wordCount":1033,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"keywords":["Bnei Anusim|Fundamentalmente Freund|Ladino|Michael Freund"],"articleSection":["FUNDAMENTALMENTE FREUND|BNEI ANUSIM","Ladino"],"inLanguage":"sp","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/","url":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/","name":"Fundamentalmente Freund: No dejen morir el Ladino - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"datePublished":"2021-05-20T14:47:57+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/#breadcrumb"},"inLanguage":"sp","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/fundamentalmente-freund-no-dejen-morir-el-ladino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Fundamentalmente Freund: No dejen morir el Ladino"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sp"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"sp","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/628be1364b127546c700d93458cf9e4c","name":"daniella","image":{"@type":"ImageObject","inLanguage":"sp","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","caption":"daniella"},"url":"https:\/\/www.shavei.org\/pt-pt\/blog\/author\/daniella\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/posts\/134541","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=134541"}],"version-history":[{"count":0,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/posts\/134541\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=134541"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=134541"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=134541"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}