{"id":134473,"date":"2021-05-20T16:47:00","date_gmt":"2021-05-20T14:47:00","guid":{"rendered":"https:\/\/www.shavei.org\/blog\/2021\/05\/20\/parash-tazria-metzora\/"},"modified":"2021-05-20T16:47:00","modified_gmt":"2021-05-20T14:47:00","slug":"parash-tazria-metzora","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/","title":{"rendered":"Parash? Tazria Metzora"},"content":{"rendered":"<p>El Rabino Eliahu Birnbaum explica: Hay tres momentos especiales, los cuales Hashem mismo acompa?a y no los maneja por medio de emisarios, uno de ellos es el Nacimiento. Se dice que los padres son socios de la creaci?n en este momento, a continuaci?n la importancia del v?nculo entre padres e hijos.<\/p>\n<p>!No se lo pierdan!<\/p>\n<p><iframe loading=\"lazy\" title=\"Parash\u00e1 Tazria Metzora\" width=\"1060\" height=\"596\" src=\"https:\/\/www.youtube.com\/embed\/OV7Z5S4WPMg?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El Rabino Eliahu Birnbaum explica: Hay tres momentos especiales, los cuales Hashem mismo acompa?a y no los maneja por medio de emisarios, uno de ellos es el Nacimiento. Se dice que los padres son socios de la creaci?n en este momento, a continuaci?n la importancia&#8230;<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[5059],"class_list":["post-134473","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-metzorparashat-hashavarab-eliahu-birnbaumshavei-israelshaveishiurimtazr"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parash? Tazria Metzora - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parash? Tazria Metzora - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"El Rabino Eliahu Birnbaum explica: Hay tres momentos especiales, los cuales Hashem mismo acompa?a y no los maneja por medio de emisarios, uno de ellos es el Nacimiento. Se dice que los padres son socios de la creaci?n en este momento, a continuaci?n la importancia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-20T14:47:00+00:00\" \/>\n<meta name=\"author\" content=\"daniella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/\"},\"author\":{\"name\":\"daniella\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/628be1364b127546c700d93458cf9e4c\"},\"headline\":\"Parash? Tazria Metzora\",\"datePublished\":\"2021-05-20T14:47:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/\"},\"wordCount\":69,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"keywords\":[\"Metzor|Parashat Hashav?a|Rab Eliahu Birnbaum|Shavei Israel|Shaveishiurim|Tazr\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"sp\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/\",\"name\":\"Parash? Tazria Metzora - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"datePublished\":\"2021-05-20T14:47:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/#breadcrumb\"},\"inLanguage\":\"sp\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/2021\\\/05\\\/20\\\/parash-tazria-metzora\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parash? Tazria Metzora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"sp\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sp\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/628be1364b127546c700d93458cf9e4c\",\"name\":\"daniella\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"sp\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"caption\":\"daniella\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-pt\\\/blog\\\/author\\\/daniella\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parash? Tazria Metzora - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/","og_locale":"en_US","og_type":"article","og_title":"Parash? Tazria Metzora - Shavei Israel","og_description":"El Rabino Eliahu Birnbaum explica: Hay tres momentos especiales, los cuales Hashem mismo acompa?a y no los maneja por medio de emisarios, uno de ellos es el Nacimiento. Se dice que los padres son socios de la creaci?n en este momento, a continuaci?n la importancia...","og_url":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/","og_site_name":"Shavei Israel","article_published_time":"2021-05-20T14:47:00+00:00","author":"daniella","twitter_card":"summary_large_image","twitter_misc":{"Written by":false},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/"},"author":{"name":"daniella","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/628be1364b127546c700d93458cf9e4c"},"headline":"Parash? Tazria Metzora","datePublished":"2021-05-20T14:47:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/"},"wordCount":69,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"keywords":["Metzor|Parashat Hashav?a|Rab Eliahu Birnbaum|Shavei Israel|Shaveishiurim|Tazr"],"articleSection":["Sin categorizar"],"inLanguage":"sp","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/","url":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/","name":"Parash? Tazria Metzora - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"datePublished":"2021-05-20T14:47:00+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/#breadcrumb"},"inLanguage":"sp","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-pt\/blog\/2021\/05\/20\/parash-tazria-metzora\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Parash? Tazria Metzora"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"sp"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"sp","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/628be1364b127546c700d93458cf9e4c","name":"daniella","image":{"@type":"ImageObject","inLanguage":"sp","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","caption":"daniella"},"url":"https:\/\/www.shavei.org\/pt-pt\/blog\/author\/daniella\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/posts\/134473","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/comments?post=134473"}],"version-history":[{"count":0,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/posts\/134473\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/media?parent=134473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/categories?post=134473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-pt\/wp-json\/wp\/v2\/tags?post=134473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}