{"id":3602,"date":"2015-06-11T07:54:33","date_gmt":"2015-06-11T05:54:33","guid":{"rendered":"https:\/\/casa-anusim.org\/?p=3602"},"modified":"2015-06-11T07:54:33","modified_gmt":"2015-06-11T05:54:33","slug":"incambiables-comentario-a-la-parasha-de-shlaj","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/","title":{"rendered":"Incambiables &#8211; Comentario a la parash? de Shlaj"},"content":{"rendered":"<p><strong><a href=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/06\/images.jpg\"><img decoding=\"async\" class=\"alignright size-full wp-image-3603\" src=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/06\/images.jpg\" alt=\"images\" width=\"275\" height=\"183\" \/><\/a><\/strong><\/p>\n<p><em>Rabino Nissan Ben Avraham<\/em><\/p>\n<p><strong>El pecado de los esp?as<\/strong><\/p>\n<p>El pecado de los esp?as es, sin duda, uno de los m?s conocidos y que marc? muy significativamente la Historia del Pueblo de Israel.<\/p>\n<p>Podemos recapitular los acontecimientos desde la salida de Egipto: al cabo de cincuenta d?as llegaron al Monte Sinai donde les fue estregada la Tor?. Mosh? permaneci? cuarenta d?as en el Monte, bajando el d?a 17 de Tamuz para descubrir que hab?an construido el Becerro de Oro. Al d?a siguiente subi? de nuevo para pedir perd?n durante otros cuarenta d?as, como dice la Tor? en el cap?tulo 32 del libro del ?xodo, bajando el ?ltimo d?a del mes de Av. Para volver a subir al d?a siguiente, el primero del mes de Elul, permaneciendo otros cuarenta d?as en el Monte para recibir las segundas Tablas de la Ley. Despu?s de este impresionante trabajo, bajaba triunfal en el d?a de Yom Kipur, despu?s de haber conseguido no tan solo el perd?n sino tambi?n la restituci?n de las Tablas perdidas.<\/p>\n<p>Dicen nuestros Sabios que ya al d?a siguiente comenz? la construcci?n del Tabern?culo. Su inauguraci?n fue el primer d?a del mes de Nis?n, y dur? doce d?as en los cuales ofreci? cada uno de los presidentes de las doce Tribus un sacrificio especial. El libro de N?meros relata la primera celebraci?n de la Salida de Egipto, en el primer aniversario del acontecimiento.<\/p>\n<p>En el d?cimo cap?tulo de este libro le?mos la semana pasada el orden de partida, en el d?a veinte del segundo mes, en el segundo a?o de la Salida de Egipto. <!--more--><\/p>\n<p>Pod?an haber llegado en once d?as a las fronteras de la Tierra Prometida, pero despu?s de tres d?as de camino (N?meros 10:33), se enredaron treinta d?as castigados por las codornices, como vimos en el pasado cap?tulo once, y otros siete esperando a que Miryam se reincorporase, como vimos al final de la parash? de B?ha?alotj?, y llegamos as? al ?ltimo d?a del mes de Siv?n, cuando fueron enviados los esp?as para investigar la Tierra Prometida. Y regresan al cabo de cuarenta d?as, en la v?spera del nueve de Av.<\/p>\n<p>Aqu? reciben el castigo de quedarse cuarenta a?os en el desierto, vagando sin rumbo fijo, seg?n les indicara la Nube que segu?a cubriendo el Tabern?culo.<\/p>\n<p><strong>El castigo rebatido<\/strong><\/p>\n<p>Pero antes de llegar a este castigo, parece que el Creador se hab?a planteado, por as? decirlo, otro castigo, ya que en el cap?tulo 14 (vers?culo 12) leemos que propon?a herir el pueblo con la peste hasta que pereciera, y convertir a los descendientes de Mosh? en el nuevo Pueblo Elegido.<\/p>\n<p>La respuesta de Mosh? no se hace esperar, y se comporta como un verdadero l?der cuya misi?n es defender a la poblaci?n que le ha sido conferida. Nosotros sabemos, adem?s, que las palabras de Mosh? reflejan la verdadera intenci?n del Creador, siendo la primera proposici?n tan solo un postulado o axioma que luego es rebatido.<\/p>\n<p>Podr?amos decir que este postulado rebatido es la opini?n del cristianismo y del islam, que creen que el Pueblo de Israel, que hab?a sido elegido por el Creador, fue abandonado en un momento de terminado de la Historia (y ?cambiado? por otro ?pueblo?), al no aceptar a Jes?s o a Mahoma, al igual que parece aqu? que podr?a haber sido abandonado para ser cambiado por el ?pueblo de Mosh??.<\/p>\n<p><strong>La respuesta de Mosh?<\/strong><\/p>\n<p>Por esto es muy importante comprender cu?l es la respuesta de Mosh? en los siete vers?culos que habla para rebatir tal opini?n.<\/p>\n<p>?13 Y oir?n los egipcios que t? sacaste a este pueblo de en medio de ellos con tu poder, 14 y dir?n a los habitantes de esta tierra, quienes han o?do que t?, oh SE?OR, est?s en medio de tu pueblo, porque ven la Presencia de tu Gloria, oh SE?OR, y tu nube est? sobre ellos; y t? vas delante de ellos de d?a en una columna de nube, y de noche en una columna de fuego. 15 Y si t? destruyes a este pueblo como a un solo hombre, entonces las naciones que han o?do de tu fama, dir?n: 16 Porque el SE?OR no pudo introducir a este pueblo a la tierra que les hab?a prometido con juramento, por eso los mat? en el desierto. 17 Pero ahora, yo te ruego que sea engrandecido el poder del Se?or, tal como t? lo has declarado, diciendo: 18 El SE?OR es lento para la ira y abundante en misericordia, y perdona la iniquidad y la transgresi?n; limpia al inocente pero no limpia al culpable y castiga la iniquidad de los padres sobre los hijos hasta la tercera y la cuarta generaci?n. 19 Perdona ahora la iniquidad de este pueblo conforme a la grandeza de tu misericordia, as? como has perdonado a este pueblo desde Egipto hasta aqu?.?<\/p>\n<p>Los comentaristas se preguntan por qu? no repiti? lo que dijo despu?s del pecado del Becerro de Oro, cuando mencion? tambi?n el juramento hecho a los Patriarcas. A esto responden que la frase comienza con una conjunci?n que parece pleon?stica pero que no lo es, sino que precisamente contin?a lo antedicho en la ocasi?n anterior y a?ade lo que veremos a continuaci?n. O sea, que no est? tan solo el juramento hecho a los Patriarcas, que los constituir?as en un Pueblo Escogido, y el argumento de que significar?a para los otros pueblos que el Creador es cruel al hacerlos salir de Egipto para matarlos en el desierto, que es lo que dijo Mosh? en el cap?tulo 32 del ?xodo. A esto a?ade que el aniquilar el Pueblo de Israel denotar?a que el Creador no tiene fuerzas para introducir al Pueblo en la Tierra que les hab?a prometido, la llamada Tierra de Cn??an.<\/p>\n<p><strong>No hay posibles ?cambiazos?<\/strong><\/p>\n<p>Los egipcios sab?an muy bien que el Pueblo en s? no ten?a los medios ni la fuerza para librarse del yugo egipcio, y que su libertad se debe ?nicamente a la ayuda divina que recibieron. Por lo tanto, si ahora perecen en el desierto, la conclusi?n de estos pueblos, el egipcio y el cananeo, ser?a que para esta conquista ya no tiene fuerzas el Creador, y se convertir?a esto en una terrible profanaci?n del Nombre Divino.<\/p>\n<p>Incluso en el caso de que se cumpliera la propuesta antedicha, de que la familia de Mosh? se convirtiera en el sucesor del Pueblo de Israel, y ella consiguiera conquistar la Tierra Prometida, esto significar?a igualmente una falta de poder del Creador, a quien ?se le hubiera escapado?, por as? decirlo, el dominio del Pueblo y hubiera tenido que sustituirlo.<\/p>\n<p>Significar?a que el amor del Creador hacia el Pueblo de Israel, a pesar de los milagros hechos en Egipto y de la Presencia Divina de modo continuo en el Tabern?culo, no era suficientemente fuerte como para cumplir las promesas hechas a los Patriarcas.<\/p>\n<p>Y a pesar de que todas estas razones no son correctas, ya que los pueblos no son capaces de reconocer el verdadero pecado de Israel y desv?an su pensamiento a otras direcciones, esto ya es suficiente para que el Creador ?no se pueda permitir? que ocurra una cosa as?.<\/p>\n<p><strong>Los Caminos del Creador<\/strong><\/p>\n<p>Nuestros Sabios nos ense?an que el Mundo tiene una meta, hay una misi?n a cumplir, y esta misi?n es que la Humanidad debe reconocer el poder absoluto del Creador, y que nada se le puede oponer, ni siquiera el ?mal comportamiento del Pueblo?, para que pueda llevar a cabo su plan. Este conocimiento emana directamente de estas palabras del gran l?der, Mosh?, precisamente en los momentos de las mayores crisis en la Historia de nuestro Pueblo. Cuando los factores m?s brillantes desaparecen y el Pueblo aparece ?desnudo? es cuando pueden encontrarse los factores m?s profundos de la elecci?n de este Pueblo maravilloso.<\/p>\n<p>En esta ?desnudez? descrita en los vers?culos que hemos citado hemos le?do precisamente que la Presencia de la Gloria divina es visible en el Tabern?culo y en las columnas de fuego y de nube que preced?an al campamento. Y por todo ello, se convierte la elecci?n del Pueblo de Israel en uno de los principales puntos de la comprensi?n de ?los Caminos del Creador?.<\/p>\n<p>Los profetas m?s tard?os tuvieron que explicar que la supuesta desaparici?n de esta Gloria manifiesta, con la destrucci?n del Templo, no significaba en absoluto que hubiera cambiado el punto de vista, como podemos ver muy claramente en el cap?tulo 36 del libro de Yejezquel (Ezequiel) que habla de la profanaci?n del Nombre del Creador cuando Israel est? en la Di?spora.<\/p>\n<p>La jactanciosa propuesta del cristianismo y del islam que ellos vienen a sustituir al Pueblo de Israel aparece en un momento en que Israel est? siendo castigado, pero solo aquellos que no comprenden los caminos del Creador, que desconocen los mensajes m?s b?sicos de la Sagrada Tor?, ser?an capaces de decir tales cosas.<\/p>\n<p>?Cu?ntas veces se han burlado de nosotros llam?ndonos ?Pueblo Elegido? con sorna y desprecio! Nunca han entendido el verdadero significado de estas palabras, de esta elecci?n divina, ya que desconocen la Historia y no son capaces de comenzar a comprender los caminos del Creador. Los que se creen m?s listos son capaces de decir incluso que los caminos del Creador ?son inescrutables? cuando, para nosotros, el estudio de estos caminos es la base de nuestra existencia, el legado de Avraham, como vemos en el G?nesis (18:19) ?Porque yo lo conozco, s? que mandar? a sus hijos y a su casa despu?s de s?, que guarden el camino del SE?OR, haciendo justicia y juicio, para que haga venir el SE?OR sobre Avraham lo que ha hablado acerca de ?l.?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Rabino Nissan Ben Avraham El pecado de los esp?as El pecado de los esp?as es, sin duda, uno de los m?s conocidos y que marc? muy significativamente la Historia del Pueblo de Israel. Podemos recapitular los acontecimientos desde la salida de Egipto: al cabo de&#8230;<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[3052,3523,778,3701],"class_list":["post-3602","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-espias","tag-pueblo-elegido","tag-rabino-nissan-ben-avraham","tag-shlaj"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Incambiables - Comentario a la parash? de Shlaj - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Incambiables - Comentario a la parash? de Shlaj - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"Rabino Nissan Ben Avraham El pecado de los esp?as El pecado de los esp?as es, sin duda, uno de los m?s conocidos y que marc? muy significativamente la Historia del Pueblo de Israel. Podemos recapitular los acontecimientos desde la salida de Egipto: al cabo de...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2015-06-11T05:54:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/06\/images.jpg\" \/>\n<meta name=\"author\" content=\"beithaanusim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/\"},\"author\":{\"name\":\"beithaanusim\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\"},\"headline\":\"Incambiables &#8211; Comentario a la parash? de Shlaj\",\"datePublished\":\"2015-06-11T05:54:33+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/\"},\"wordCount\":1726,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/images.jpg\",\"keywords\":[\"Esp?as\",\"Pueblo Elegido\",\"Rabino Nissan Ben Avraham\",\"Shlaj\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/\",\"name\":\"Incambiables - Comentario a la parash? de Shlaj - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/images.jpg\",\"datePublished\":\"2015-06-11T05:54:33+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/#primaryimage\",\"url\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/images.jpg\",\"contentUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/images.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/06\\\/11\\\/incambiables-comentario-a-la-parasha-de-shlaj\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Incambiables &#8211; Comentario a la parash? de Shlaj\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\",\"name\":\"beithaanusim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"beithaanusim\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/author\\\/beithaanusim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Incambiables - Comentario a la parash? de Shlaj - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/","og_locale":"pt_BR","og_type":"article","og_title":"Incambiables - Comentario a la parash? de Shlaj - Shavei Israel","og_description":"Rabino Nissan Ben Avraham El pecado de los esp?as El pecado de los esp?as es, sin duda, uno de los m?s conocidos y que marc? muy significativamente la Historia del Pueblo de Israel. Podemos recapitular los acontecimientos desde la salida de Egipto: al cabo de...","og_url":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/","og_site_name":"Shavei Israel","article_published_time":"2015-06-11T05:54:33+00:00","og_image":[{"url":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/06\/images.jpg","type":"","width":"","height":""}],"author":"beithaanusim","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Est. tempo de leitura":"9 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/"},"author":{"name":"beithaanusim","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6"},"headline":"Incambiables &#8211; Comentario a la parash? de Shlaj","datePublished":"2015-06-11T05:54:33+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/"},"wordCount":1726,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/#primaryimage"},"thumbnailUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/06\/images.jpg","keywords":["Esp?as","Pueblo Elegido","Rabino Nissan Ben Avraham","Shlaj"],"articleSection":["Sin categorizar"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/","url":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/","name":"Incambiables - Comentario a la parash? de Shlaj - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/#primaryimage"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/#primaryimage"},"thumbnailUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/06\/images.jpg","datePublished":"2015-06-11T05:54:33+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/#primaryimage","url":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/06\/images.jpg","contentUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/06\/images.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/06\/11\/incambiables-comentario-a-la-parasha-de-shlaj\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/"},{"@type":"ListItem","position":2,"name":"Incambiables &#8211; Comentario a la parash? de Shlaj"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6","name":"beithaanusim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"beithaanusim"},"url":"https:\/\/www.shavei.org\/pt-br\/blog\/author\/beithaanusim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/3602","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/comments?post=3602"}],"version-history":[{"count":0,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/3602\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/media?parent=3602"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/categories?post=3602"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/tags?post=3602"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}