{"id":3391,"date":"2015-02-10T15:37:04","date_gmt":"2015-02-10T13:37:04","guid":{"rendered":"https:\/\/casa-anusim.org\/?p=3391"},"modified":"2015-02-10T15:37:04","modified_gmt":"2015-02-10T13:37:04","slug":"los-orfebres-judios-nociones-sobre-judaismo","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/","title":{"rendered":"Los Orfebres Jud?os &#8211; Nociones deJuda?smo"},"content":{"rendered":"<p><strong><a href=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/02\/05_orfebre_13.jpg\"><img decoding=\"async\" class=\"alignright size-medium wp-image-3392\" src=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/02\/05_orfebre_13.jpg?w=300\" alt=\"05_orfebre_13\" width=\"300\" height=\"200\" \/><\/a><\/strong><em>Por Rabino Nissan Ben Avraham<\/em><\/p>\n<p><strong>El Segundo Mandamiento<\/strong><\/p>\n<p>Cincuenta d?as despu?s de la Salida de Egipto estaban los Hijos de Israel a los pies del Monte Sinai, escuchando la Palabra del Creador, el llamado Dec?logo.<\/p>\n<p>Hay una famosa pol?mica entre los Sabios de Israel si el llamado Primer Mandamiento del Dec?logo es realmente un mandamiento o no. Hay quien opina que no es un mandamiento, ya que en ?l no se ordena ni se proh?be nada, sino que simplemente afirma que (?xodo 20:2): ?Yo soy el Se?or tu D?ios, que te sac? de la Tierra de Egipto, de casa de servidumbre?, como pr?logo a los mandamientos que vienen a continuaci?n en el Dec?logo y en el resto de los 613 Mandamientos de la Tor?. Pero precisamente Maim?nides escribe que de ah? se aprenden los principios de fe de la existencia del Creador y de que gu?a el mundo seg?n sus planes, y esto es un mandamiento: creer en Su existencia y en su providencia.<\/p>\n<p>A continuaci?n viene el Segundo Mandamiento, que en realidad son cuatro prohibiciones. Comienza con el vers?culo 3 diciendo que: ?No tendr?s otros dioses ante M??; el vers?culo 4 a?ade que: ?No te har?s escultura ni ning?n dibujo de lo que hay arriba en el cielo o abajo en la tierra, o en las aguas debajo de la tierra?; los vers?culos 5 y 6 contin?an diciendo que: ?No te postrar?s ante ellos no lis adorar?s, porque Yo soy el Se?or tu D?ios, un D?ios celoso que recuerda la iniquidad de los padres sobre los hijos hasta la tercera o cuarta generaci?n de los que Me odian; y hago bondad por millares a los que me aman y guardan Mis mandamientos?.<\/p>\n<p>En la redacci?n del Dec?logo hay dos detalles importantes, que han causado la confusi?n de algunos int?rpretes, o mejor dicho: han servido de excusa para aquellos que quer?an tergiversar el sentido de la Palabra Divina. Se trata de que hay lo que podr?amos llamar ?punto y aparte? entre los mandamientos, que separan visiblemente en el texto hebreo entre un mandamiento y otro, con dos excepciones. La primera es que entre los dos primeros Mandamientos no hay ?punto y aparte?, y la segunda es que el d?cimo Mandamiento, ?no codiciar?, est? partido en dos por medio de un ?punto y aparte?. Por ello, la tradici?n cristiana ?borra? el segundo mandamiento y, para cumplir con los ?Diez mandamientos?, divide el ?ltimo en dos. Sin entrar ahora en el motivo de la extra?a redacci?n, nuestra Tradici?n deja bien claro que la divisi?n es como yo la he expuesto y, por supuesto, no como la tradici?n cristiana. Y aunque tuvieran raz?n, que no la tienen, no por ello desaparecen los vers?culos 3-7 que proh?ben la idolatr?a.<!--more--><\/p>\n<p><strong>La gravedad de la idolatr?a<\/strong><\/p>\n<p>Efectivamente, la idolatr?a es uno de los errores m?s graves de la Humanidad, ya que al ?hacerse dioses? del tama?o que el hombre quer?a, estaba reduciendo la divinidad en un juguete del que ya no deb?a temer ni hacer caso de sus palabras. Los grandes profetas dedicaron muchos vers?culos a advertir al Pueblo de Israel que abandonaran las costumbres de los id?latras, tanto si pretend?an adorar a otras fuerzas naturales o sobrenaturales, como si no quer?an m?s que personalizar al Creador con una imagen palpable, como ocurri? con el Becerro de Oro.<\/p>\n<p>La Mishn? y el talmud dedican m?ltiples cap?tulos y p?ginas a regular c?mo comportarse en una sociedad de id?latras en las que los jud?os se ven obligados a convivir, sin caer no tan solo en la idolatr?a sino tampoco en nada que se le parezca, para no ayudar o animar a los id?latras en sus errores.<\/p>\n<p>Es cierto que ha cambiado mucho la Humanidad desde la ?poca de nuestros Patriarcas, ya que, seg?n el Talmud, Avraham ten?a cuatrocientos cap?tulos en su tratado de Idolatr?a, mientras que en el nuestro hay solo cinco, lo que significa que en nuestra ?poca ya no es tan grave.<\/p>\n<p><strong>El Cristianismo<\/strong><\/p>\n<p>Escribe Maim?nides en el pen?ltimo cap?tulo de su obra enciclop?dica de Mishn? Tor?, que los planes del Creador son inescrutables, ya que tanto el Cristianismo como el Islam, a pesar de ser grandes errores y que los jud?os no pueden ni por un momento hacerles el menor caso, han servido para que las nociones del Juda?smo sean conocidas universalmente. Unos dicen que ?los mandamientos est?n pasados de moda?, y otros dices que ?son cosas profundas que no se pueden entender?; pero cuando venga el Mash?aj de verdad, todos entender?n su error y volver?n a la verdad.<\/p>\n<p>De todos modos, el mismo Maim?nides escribe en las Leyes de Idolatr?a (cap. 9, art?culo 4) que los cristianos son id?latras. El motivo es que adoran a una persona humana convertida en ?dios?, o en ?hijo de dios?, tanto si le hacen una imagen ?humana? como si se limitan a una sencilla cruz: esto es un ?dolo y est? prohibido. Incluso por el hecho de adorar a una persona humana divinizada, ya est?n trasgrediendo el Segundo Mandamiento, y no es de extra?ar que lo hayan borrado de los Catecismos y los libros de estudio.<\/p>\n<p><strong>Se paga al final<\/strong><\/p>\n<p>De aqu?, pasamos a otro tema completamente diferente en la jurisprudencia hebrea, para relacionar ambos temas al final.<\/p>\n<p>Vamos a hablar de un obrero que trabaja por encargo de alguien, y la Tor? dice que debemos pagarle en el mismo d?a, y quien no lo hace transgrede el mandamiento que dice ?en su d?a le dar?s su sueldo? (Dvarim 24:15). Por lo tanto, debemos asegurarnos que no pase ni un solo d?a sin haberle pagado. Y si acaba su trabajo media hora, o menos, antes de la puesta del sol, debemos pagarle antes de la puesta del sol, ya que entonces empieza otro d?a.<\/p>\n<p>La cuesti?n es que cuando se trata de un trabajo que dura varios d?as, el mandamiento de pagar en su d?a comienza solo en el ?ltimo d?a. Mejor dicho: lo que cuenta es el momento en que da su ?ltimo golpe (seg?n la expresi?n talm?dica, que pone por ejemplo a un herrero), y por lo tanto, si ha estado trabajando todo el d?a, pero el ?ltimo golpe lo ha dado ya despu?s de la puesta del sol, en que comienza un nuevo d?a, tenemos m?s tiempo para pagarle.<\/p>\n<p>Esto es lo que el Talmud dice que ?el encargo se paga al final?, o sea, que solo al acabar su trabajo se convierte en propiedad del que ha hecho el encargo, y hasta ahora pertenec?a al obrero (Baba Mets?a 110b).<br \/>\nLos orfebres jud?os<\/p>\n<p>Sabemos que muchos jud?os se dedicaron a la orfebrer?a a lo largo de la historia de nuestra Di?spora, ya que muchos otros oficios les estaban vedados y necesitaban algo que pudieran ejercer en cualquier lugar, al ser expulsados de un lugar a otro.<\/p>\n<p>Y muchas veces los plateros jud?os, o los conversos, despu?s de haber sido forzados a convertirse al Cristianismo, recib?an encargos de las parroquias cercanas para que preparasen adornos para las iglesias.<\/p>\n<p>Est? perfectamente claro que la gran mayor?a de estos encargos eran pura idolatr?a y al preparar los encargos estaban transgrediendo las leyes contra idolatr?a que hemos visto al principio, y en tiempos del Templo en que hab?a un tribunal capacitado, les hubieran dado el castigo decretado en la Tor?. Aunque el orfebre no creyera en las im?genes que estaba preparando, o para las que estaba creando adornos, le estaba completamente prohibido hacerlo.<\/p>\n<p>Pero, curiosamente, al tener que decidir si el sueldo ganado por este trabajo prohibido era l?cito o no, Maim?nides nos prepara una respuesta sorprendente. El jud?o, o el converso, que no creen en la idolatr?a cristiana no crean, por lo tanto, un ?dolo prohibido: se convertir? en ?dolo cuando llegue a manos del id?latra que lo ha encargado. Es verdad que el jud?o no deber?a haberlo hecho y se merece un castigo por ello, pero esto no implica que haya cometido ?idolatr?a?.<\/p>\n<p>Ya hemos visto que solo cuando termina el encargo, en el ?ltimo golpe del martillo, se convierte en propiedad de quien lo ha encargado, y este ?ltimo golpe, seg?n explica Maim?nides, no tiene un valor m?nimo que le d? importancia al trabajo. Por lo tanto, el sueldo por este trabajo no le est? prohibido.<\/p>\n<p>No estamos hablando aqu? de quien prepara im?genes (cruces, etc.) para tener en su escaparate, listas para ser vendidas ya que en este caso est? claro que el precio, a posteriori, es leg?timo. A?n as?, el trabajo est? gravemente prohibido y tal vez deber?a estarle prohibido no tan solo fabricar sino tambi?n vender estos art?culos, ya que est? poniendo un obst?culo ante los ciegos que no comprenden la gravedad de la idolatr?a. Y aun cuando puedan ir a otra tienda a comprar los objetos y con ello se perjudican las ganancias del orfebre jud?o, no debe preocuparse por ello, ya que lo que ganar? en ?ste Mundo y en el venidero es much?simo m?s valioso que las pocas perdidas que pueda tener a causa del cumplimiento de su deber como jud?o.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rabino Nissan Ben Avraham El Segundo Mandamiento Cincuenta d?as despu?s de la Salida de Egipto estaban los Hijos de Israel a los pies del Monte Sinai, escuchando la Palabra del Creador, el llamado Dec?logo. Hay una famosa pol?mica entre los Sabios de Israel si&#8230;<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[3173,3329,3339,3390,3430,3445,778],"class_list":["post-3391","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-idolatria","tag-maimonides","tag-mandamientos","tag-mishne-tora","tag-nociones-de-judaismo","tag-orfebre","tag-rabino-nissan-ben-avraham"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los Orfebres Jud?os - Nociones deJuda?smo - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los Orfebres Jud?os - Nociones deJuda?smo - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"Por Rabino Nissan Ben Avraham El Segundo Mandamiento Cincuenta d?as despu?s de la Salida de Egipto estaban los Hijos de Israel a los pies del Monte Sinai, escuchando la Palabra del Creador, el llamado Dec?logo. Hay una famosa pol?mica entre los Sabios de Israel si...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2015-02-10T13:37:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/02\/05_orfebre_13.jpg?w=300\" \/>\n<meta name=\"author\" content=\"beithaanusim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/\"},\"author\":{\"name\":\"beithaanusim\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\"},\"headline\":\"Los Orfebres Jud?os &#8211; Nociones deJuda?smo\",\"datePublished\":\"2015-02-10T13:37:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/\"},\"wordCount\":1638,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/05_orfebre_13.jpg?w=300\",\"keywords\":[\"Idolatr\",\"Maim?nides\",\"Mandamientos\",\"Mishn? Tor\",\"Nociones de Juda?smo\",\"Orfebre\",\"Rabino Nissan Ben Avraham\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/\",\"name\":\"Los Orfebres Jud?os - Nociones deJuda?smo - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/05_orfebre_13.jpg?w=300\",\"datePublished\":\"2015-02-10T13:37:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/05_orfebre_13.jpg?w=300\",\"contentUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/02\\\/05_orfebre_13.jpg?w=300\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/02\\\/10\\\/los-orfebres-judios-nociones-sobre-judaismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los Orfebres Jud?os &#8211; Nociones deJuda?smo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\",\"name\":\"beithaanusim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"beithaanusim\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/author\\\/beithaanusim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los Orfebres Jud?os - Nociones deJuda?smo - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/","og_locale":"pt_BR","og_type":"article","og_title":"Los Orfebres Jud?os - Nociones deJuda?smo - Shavei Israel","og_description":"Por Rabino Nissan Ben Avraham El Segundo Mandamiento Cincuenta d?as despu?s de la Salida de Egipto estaban los Hijos de Israel a los pies del Monte Sinai, escuchando la Palabra del Creador, el llamado Dec?logo. Hay una famosa pol?mica entre los Sabios de Israel si...","og_url":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/","og_site_name":"Shavei Israel","article_published_time":"2015-02-10T13:37:04+00:00","og_image":[{"url":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/02\/05_orfebre_13.jpg?w=300","type":"","width":"","height":""}],"author":"beithaanusim","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/"},"author":{"name":"beithaanusim","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6"},"headline":"Los Orfebres Jud?os &#8211; Nociones deJuda?smo","datePublished":"2015-02-10T13:37:04+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/"},"wordCount":1638,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/#primaryimage"},"thumbnailUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/02\/05_orfebre_13.jpg?w=300","keywords":["Idolatr","Maim?nides","Mandamientos","Mishn? Tor","Nociones de Juda?smo","Orfebre","Rabino Nissan Ben Avraham"],"articleSection":["Sin categorizar"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/","url":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/","name":"Los Orfebres Jud?os - Nociones deJuda?smo - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/#primaryimage"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/#primaryimage"},"thumbnailUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/02\/05_orfebre_13.jpg?w=300","datePublished":"2015-02-10T13:37:04+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/#primaryimage","url":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/02\/05_orfebre_13.jpg?w=300","contentUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/02\/05_orfebre_13.jpg?w=300"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/02\/10\/los-orfebres-judios-nociones-sobre-judaismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/"},{"@type":"ListItem","position":2,"name":"Los Orfebres Jud?os &#8211; Nociones deJuda?smo"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6","name":"beithaanusim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"beithaanusim"},"url":"https:\/\/www.shavei.org\/pt-br\/blog\/author\/beithaanusim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/3391","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/comments?post=3391"}],"version-history":[{"count":0,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/3391\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/media?parent=3391"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/categories?post=3391"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/tags?post=3391"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}