{"id":3335,"date":"2015-01-05T09:26:24","date_gmt":"2015-01-05T07:26:24","guid":{"rendered":"https:\/\/casa-anusim.org\/?p=3335"},"modified":"2015-01-05T09:26:24","modified_gmt":"2015-01-05T07:26:24","slug":"la-verdadera-felicidad","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/","title":{"rendered":"La verdadera felicidad"},"content":{"rendered":"<p><em>Por Rabino Yitzjak Abud<a href=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/01\/fotoliaclown_28656651_xs.jpg\"><img decoding=\"async\" class=\"alignright size-medium wp-image-3336\" src=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/01\/fotoliaclown_28656651_xs.jpg?w=300\" alt=\"Clowns\" width=\"300\" height=\"203\" \/><\/a><\/em><\/p>\n<p>Los jajamim han expresado que el vers?culo, ?cuando comas del esfuerzo de tus manos, ser?s feliz y te ir? bien? (Tehilim 128:2), significa ?feliz? en este mundo y ?te ir? bien? en el Mundo Venidero (Pirk? Abot 4:1).<\/p>\n<p>En ese pasaje, los sabios hablan sobre la importancia de ser felices con lo que se tiene.<\/p>\n<p>En el vers?culo est? escrito, ?? del esfuerzo de tus manos?? con cierta intenci?n: Que sea un esfuerzo solamente de las manos, de los brazos, de las piernas, un esfuerzo f?sico. Pero no un esfuerzo del coraz?n y la mente.<\/p>\n<p>En otras palabras, se debe trabajar, pero que esto no abrume al individuo. Que no ?meta de lleno? su mente y su coraz?n. Que ?stos ?ltimos est?n libres para el Servicio Divino, que no sea su trabajo lo que ocupe toda su mente y todo su coraz?n.<\/p>\n<p>El trabajo debe ser realizado con completa responsabilidad, pero el esfuerzo principal de esos ?rganos debe ser para lo espiritual.<\/p>\n<p>Basado en las palabras del Rebbe de Kotzk<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rabino Yitzjak Abud Los jajamim han expresado que el vers?culo, ?cuando comas del esfuerzo de tus manos, ser?s feliz y te ir? bien? (Tehilim 128:2), significa ?feliz? en este mundo y ?te ir? bien? en el Mundo Venidero (Pirk? Abot 4:1). En ese pasaje,&#8230;<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[3033,3582,3605,3648,3678,3751],"class_list":["post-3335","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-el-mundo-venidero","tag-rabino-yitzjak-aboud","tag-rebbe-de-kotzk","tag-salmos","tag-servicio-divino","tag-tehilim"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La verdadera felicidad - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La verdadera felicidad - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"Por Rabino Yitzjak Abud Los jajamim han expresado que el vers?culo, ?cuando comas del esfuerzo de tus manos, ser?s feliz y te ir? bien? (Tehilim 128:2), significa ?feliz? en este mundo y ?te ir? bien? en el Mundo Venidero (Pirk? Abot 4:1). En ese pasaje,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-05T07:26:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/01\/fotoliaclown_28656651_xs.jpg?w=300\" \/>\n<meta name=\"author\" content=\"beithaanusim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/\"},\"author\":{\"name\":\"beithaanusim\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\"},\"headline\":\"La verdadera felicidad\",\"datePublished\":\"2015-01-05T07:26:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/\"},\"wordCount\":183,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/fotoliaclown_28656651_xs.jpg?w=300\",\"keywords\":[\"el Mundo Venidero\",\"Rabino Yitzjak Aboud\",\"Rebbe de Kotzk\",\"Salmos\",\"Servicio Divino\",\"Tehilim\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/\",\"name\":\"La verdadera felicidad - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/fotoliaclown_28656651_xs.jpg?w=300\",\"datePublished\":\"2015-01-05T07:26:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/#primaryimage\",\"url\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/fotoliaclown_28656651_xs.jpg?w=300\",\"contentUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2015\\\/01\\\/fotoliaclown_28656651_xs.jpg?w=300\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2015\\\/01\\\/05\\\/la-verdadera-felicidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La verdadera felicidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\",\"name\":\"beithaanusim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"beithaanusim\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/author\\\/beithaanusim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La verdadera felicidad - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/","og_locale":"pt_BR","og_type":"article","og_title":"La verdadera felicidad - Shavei Israel","og_description":"Por Rabino Yitzjak Abud Los jajamim han expresado que el vers?culo, ?cuando comas del esfuerzo de tus manos, ser?s feliz y te ir? bien? (Tehilim 128:2), significa ?feliz? en este mundo y ?te ir? bien? en el Mundo Venidero (Pirk? Abot 4:1). En ese pasaje,...","og_url":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/","og_site_name":"Shavei Israel","article_published_time":"2015-01-05T07:26:24+00:00","og_image":[{"url":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/01\/fotoliaclown_28656651_xs.jpg?w=300","type":"","width":"","height":""}],"author":"beithaanusim","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/"},"author":{"name":"beithaanusim","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6"},"headline":"La verdadera felicidad","datePublished":"2015-01-05T07:26:24+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/"},"wordCount":183,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/#primaryimage"},"thumbnailUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/01\/fotoliaclown_28656651_xs.jpg?w=300","keywords":["el Mundo Venidero","Rabino Yitzjak Aboud","Rebbe de Kotzk","Salmos","Servicio Divino","Tehilim"],"articleSection":["Sin categorizar"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/","url":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/","name":"La verdadera felicidad - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/#primaryimage"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/#primaryimage"},"thumbnailUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/01\/fotoliaclown_28656651_xs.jpg?w=300","datePublished":"2015-01-05T07:26:24+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/#primaryimage","url":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/01\/fotoliaclown_28656651_xs.jpg?w=300","contentUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2015\/01\/fotoliaclown_28656651_xs.jpg?w=300"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2015\/01\/05\/la-verdadera-felicidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/"},{"@type":"ListItem","position":2,"name":"La verdadera felicidad"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6","name":"beithaanusim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"beithaanusim"},"url":"https:\/\/www.shavei.org\/pt-br\/blog\/author\/beithaanusim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/3335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/comments?post=3335"}],"version-history":[{"count":0,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/3335\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/media?parent=3335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/categories?post=3335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/tags?post=3335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}