{"id":282,"date":"2011-12-01T17:20:32","date_gmt":"2011-12-01T15:20:32","guid":{"rendered":"https:\/\/beithaanusim.wordpress.com\/?p=282"},"modified":"2011-12-01T17:20:32","modified_gmt":"2011-12-01T15:20:32","slug":"travesiajudia","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/","title":{"rendered":"Por doquier: cr?nicas de una traves?a jud"},"content":{"rendered":"<div>\n<p>?QUI?NES SON LOS ANUSIM DE NUESTROS D?AS?<\/p>\n<p>En t?rminos generales, solemos pensar que los anusim son una especie extinguida, que s?lo se conserva en los libros de historia y los documentos polvorientos de tiempos de la Inquisici?n. Pero no es as?; hay anusim y descendientes de anusim que viven hasta el presente en todo el mundo y que quieren volver a unir sus destinos al del pueblo jud?o.<\/p>\n<p>El fen?meno de la vida oculta del juda?smo de Espa?a constituye probablemente uno de los cap?tulos m?s apasionantes de la historia jud?a, y sus testimonios siguen siendo vigentes hasta el presente. A pesar de las numerosas dificultades, los descendientes de anusim lograron preservarse y preservar los lazos con sus ra?ces jud?as y la sensaci?n de pertenencia al pueblo jud?o durante m?s de 600 a?os.<\/p>\n<p><!--more--><\/p>\n<p>Como se sabe, los anusim son jud?os que en tiempos de la Inquisici?n fueron forzados a convertirse al cristianismo, pero que siguieron cumpliendo los preceptos judaicos en secreto.<\/p>\n<p>Los anusim se caracterizan por diversos nombres y diferentes historias. El concepto conocido en Espa?a y Portugal era el de ?marranos? (un apodo despectivo que compara a los anusim con cerdos). Asimismo, el t?rmino de ?criptojud?os? fue muy difundido, cristianos jud?os o conversos, es decir, jud?os que hab?an cambiado de religi?n. En otros lugares los llamaban ?cristianos nuevos? para se?alar su reciente incorporaci?n al cristianismo. En Palma de Mallorca (una isla al sur de Espa?a) los llaman ?chuetas?. Hoy en d?a, los descendientes de los marranos, chuetas o cristianos nuevos prefieren definirse como ?anusim? o descendientes de anusim. El denominador com?n a todos estos nombres es el hecho de que todos fueron forzados a abandonar el juda?smo y obligados a aceptar la fe cristiana contra su voluntad, a pesar de que en sus corazones y en sus hogares segu?an manteniendo la fe y la tradici?n jud?a a diferentes niveles.<\/p>\n<p>Cabe suponer que no todos saben que las leyes de la Inquisici?n y sus iniquidades subsistieron hasta el siglo XIX. Las leyes de la Inquisici?n, se revocaron formal y definitivamente en Espa?a s?lo en 1834; de hecho, en algunos pa?ses de Am?rica del Sur y en Angola las persecuciones prosiguieron hasta fines del siglo XIX.<\/p>\n<p>Han pasado m?s de 600 a?os desde la aparici?n del fen?meno de una vida jud?a oculta en la Pen?nsula Ib?rica, y menos de 200 a?os desde la revocaci?n de las leyes de la Inquisici?n en Espa?a, Portugal y el continente americano. A pesar de eso, las huellas de los descendientes de anusim no s?lo que no desaparecieron de la historia, sino que siguieron existiendo activamente hasta el presente.<\/p>\n<p>Hoy en d?a se conoce con certeza la existencia de grupos de anusim y descendientes de anusim en diferentes lugares: algunos siguen viviendo en Espa?a y Portugal y se consideran descendientes de jud?os de tiempos de la Inquisici?n; otros siguieron manteniendo su fe y su identidad en los pa?ses de dispersi?n de los anusim que huyeron de la conversi?n forzada, como Brasil, M?xico, Nueva M?xico en los Estados Unidos y varios pa?ses en Am?rica del Sur.<\/p>\n<p>Los descendientes de anusim est?n recuperando a nivel individual y comunitario la conciencia de pertenencia y el v?nculo con sus antepasados. Miles de anusim se encuentran actualmente en proceso de b?squeda espiritual y nacional, a fin de retornar a sus ra?ces jud?as. Miles estudian juda?smo en seminarios y clases, participan en la vida comunitaria, en debates y en estudios en sitios de Internet creados para ellos. En general, el juda?smo se mantuvo a nivel individual, fundamentalmente en zonas rurales en las cuales las caracter?sticas sociales les permit?an preservar su identidad.<\/p>\n<p>Estos descendientes de anusim afirman provenir de la maravillosa generaci?n de anusim que mantuvieron su juda?smo en secreto y que transmitieron de generaci?n en generaci?n la tradici?n de su condici?n jud?a, generalmente por v?a oral. En casi todos los relatos, la informaci?n sobre la condici?n jud?a se entregaba antes del fallecimiento del abuelo o la abuela, que quer?an legar su secreto a las generaciones venideras. La identidad de los anusim se manten?a siempre oculta, sin difundirla ni ponerla en conocimiento de otras personas. El secreto de los anusim puede ser descripto como una especie de red de espionaje subterr?nea que se preserv? oculta durante m?s de 600 a?os. La dif?cil realidad que forzaba a los anusim a ocultar su fe y su identidad jud?a, dificult? no s?lo el cumplimiento de los preceptos sino tambi?n su estudio y transmisi?n a las generaciones venideras. Se puede entender por qu? la vida secreta de los jud?os revisti? diversas formas y aspectos, y costumbres diferentes s?lo si se toma en cuenta el hecho de que este fen?meno existi? durante varios siglos en muchas regiones apartadas entre s?.<\/p>\n<p>Recientemente me encontr? en Espa?a con un hombre de m?s de 70 a?os que naci? y vivi? toda su vida en el pueblo de Sirat. Seg?n todos los datos, en esa regi?n de Espa?a (Castell?n) no hab?a jud?os desde que los reyes les dieron la posibilidad de convertirse al cristianismo o abandonar el pa?s. Pero ese hombre llevaba en el brazo? un talit que su madre le hab?a tejido a mano 60 a?os atr?s para que supiera de d?nde ven?a y a qu? pueblo pertenec?a. Era un talit blanco con franjas azules, que conservaba para legarlo a sus hijos. Ese hombre, Francisco Bellido, sab?a recitar (con gran emoci?n) las plegarias Shma Israel y Mod? An? en hebreo, tal como se las hab?a ense?ado su abuelo. En su casa hab?a una mezuz? de arcilla del siglo XVII, no en la puerta exterior, por miedo a las autoridades, sino en una puerta interna; al pasar por ella la familia sol?a besarla. Esta tradici?n hab?a pasado de generaci?n en generaci?n, sin libros, ni rabinos ni instituciones de estudio de la Tor??<\/p>\n<p>La historia se repite? Lo que los reyes Fernando e Isabel trataron de hacer en Espa?a en el siglo XV ? borrar todo rastro de los jud?os y el juda?smo a trav?s de la expulsi?n y la conversi?n forzada en Espa?a y Portugal ? vuelve a despertar? Un n?mero considerable de descendientes de estas v?ctimas resurge de la historia y quiere fortalecer al pueblo jud?o y enmendar aquel cap?tulo amargo de la Inquisici?n? Cabe suponer que los reyes de Espa?a y Portugal se revolver?an en sus tumbas ante esta noticia?<\/p>\n<p>Por supuesto, la historia de los anusim no es un bloque uniforme. Hay diferentes grupos y muchas divisiones entre ellos, y no todos son descendientes biol?gicos de los anusim de Espa?a y Portugal; pero la mayor parte puede ser considerada como sus descendientes espirituales, teniendo en cuenta las proyecciones hal?jicas aplicables a cada grupo.<\/p>\n<p>Hoy en d?a existen anusim concretos, que han vivido hasta ahora como jud?os ocultos, preservando la fe en un solo D-os, cumpliendo los preceptos en secreto y contrayendo matrimonios endog?micos durante m?s de 600 a?os. Ellos saben que son jud?os y que su identidad jud?a se preserv? a pesar de que durante siglos pensaron que todo el pueblo jud?o hab?a sido aniquilado y que ellos eran sus ?ltimos remanentes sobre la faz de la tierra. Hay anusim seg?n la Halaj?, cuyas familias conservaron la continuidad biol?gica, pero no la identidad jud?a: manten?an algunas costumbres y se casaban entre s?, pero no sab?an explicar por qu? lo hac?an? Los viernes encend?an velas en secreto y contra?an matrimonios endog?micos, pero no lo ve?an como un acto religioso o jud?o. Por otra parte, hay anusim con identidad jud?a que saben que descienden desde hace siglos de una familia jud?a, que probablemente no conservaron la identidad biol?gica y se casaron con no jud?os, pero que se sienten descendientes de anusim y orgullosos de sus ra?ces jud?as, y por ende desean reavivarlas. (Con respecto a esta clase de anusim, Abrabanel escribi? que ?los consideramos no jud?os?; en su opini?n ?habr?n de retornar al juda?smo; D?os no ha desesperado de ellos y con su inmensa misericordia los har? retornar a su Tor??). Hay algunos anusim que descienden de madre jud?a, y otros de padre jud?o, pero que se sienten jud?os en todo sentido (como los jud?os de Rusia, pa?s que determina la religi?n de una persona seg?n la de su padre). Lamentablemente, tambi?n hay cristianos evangelistas y mesi?nicos que tratan de infiltrarse en el pueblo jud?o asegurando que descienden de anusim.<\/p>\n<p>El tema de los anusim y sus descendientes no ha sido examinado a fondo por los estudiosos rab?nicos de nuestro tiempo. No abundan las respuestas y los dict?menes que se refieren a ellos y que tratan de proponer una forma de hacerlos retornar al seno de nuestro pueblo en estos tiempos. Cabe suponer que la raz?n principal de ello es que los anusim siguen replegados sobre s? mismos, como desde hace siglos. S?lo despu?s del cambio de gobierno en Espa?a (la muerte de Franco) y Portugal (el fin de la dictadura y el comienzo de la democracia en 1975), los descendientes de anusim se sintieron libres para exponer sus sentimientos y pedidos.<\/p>\n<p>Por supuesto, en las generaciones posteriores a la expulsi?n de Espa?a y Portugal (en los siglos XV, XVI y XVII) hubo muchos estudiosos que examinaron la condici?n de quienes se hab?an visto forzados a aceptar el cristianismo y bautizarse, pero hab?an conservado en sus corazones la fe jud?a. Desde entonces y hasta el presente, el tema de los anusim sigui? existiendo no s?lo en lo m?s profundo de los corazones de sus descendientes sino tambi?n en secreto en el mundo rab?nico. A partir del siglo XVIII, el tema desapareci? casi por completo de la orden del d?a jud?a y nacional.<\/p>\n<p>Pero los anusim y su situaci?n volvieron a ser objeto de an?lisis en Elul de 5689, en el Consejo de los Grandes Sabios de la Tor? en tiempos de la Segunda Gran Asamblea; todos acordaron sobre la necesidad de acercarlos al pueblo jud?o. El Rabino Zirelson se?al? en su libro de responsa y homil?as Maarajei Lev: ?Recibir a nuestros hermanos alejados, los anusim de Espa?a y Portugal, con los brazos abiertos para hacerlos retornar bajo las alas de la Presencia de D?os?. El Rabino Guedalia Felder escribi? en su libro Najalat Zvi: ?De lo antedicho se debe entender que el juda?smo no odia a los anusim, sino que los ha considerado ajenos a los dem?s pueblos, y a quienes quieren retornar se les dice: ?Hermanos alejados, vuelvan al seno de su pueblo; sepan que la gente dice que un mirto que se encuentra entre las espinas se llama mirto, ?se es su nombre? [una persona no cambia su naturaleza aunque no se encuentre en su lugar]?.<\/p>\n<p>Tambi?n el Rabino Yehuda Halevi Ushpizai z?l, rabino y titular del Tribunal Rab?nico de Ramat Gan, escribi?: ?Ahora creemos que D?os ha recordado a su pueblo y su tierra, y que hemos tenido el privilegio de despertar del exilio, tal como lo prometiera el profeta Ezequiel: ?Pero vosotros, montes de Israel, echar?is vuestras ramas y producir?is vuestro fruto para mi pueblo Israel; porque pronto vendr?n?? Debemos despertar a los anusim de Espa?a y decirles que el D?os de Israel los llama, que retornen al pueblo jud?o? En su libro sobre la Tor? eterna, Don Isaac Abrabanel los ha perpetuado y ha prometido que los anusim de Espa?a volver?n al juda?smo?.<\/p>\n<p>El Rabino Haim David Halevi z?l escribi?: ?A partir de ahora, una de las maravillas de la futura redenci?n milagrosa del pueblo jud?o ser? el retorno de los hijos perdidos y extraviados al seno del juda?smo. Y si tambi?n los descendientes de los anusim de Espa?a y Am?rica quieren retornar al juda?smo, veremos en ello parte del ?inicio de la redenci?n???<\/p>\n<p>El Rabino Mordejai Eliahu Shelita escribi?: ?Puesto que ha pasado mucho tiempo desde la ?poca de los anusim hasta el presente, y existe el temor de que se hayan mezclado con no jud?os, ?debemos atraerlos con benevolencia?, es decir, se los debe elogiar porque quieren cumplir abiertamente con los preceptos de la Tor\u1505 Tambi?n el Primado de Sion, el Rabino Shlomo Moshe Amar Shelita anunci? la creaci?n de una comisi?n que examine la pertenenia de los anusim al pueblo jud?o y la forma adecuada de hacerlos retornar.<\/p>\n<p><em><strong>Rab Eliahu Birnbaum<\/strong><\/em><br \/>\n<em><strong>25\/02\/2008<\/strong><\/em><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>?QUI?NES SON LOS ANUSIM DE NUESTROS D?AS? En t?rminos generales, solemos pensar que los anusim son una especie extinguida, que s?lo se conserva en los libros de historia y los documentos polvorientos de tiempos de la Inquisici?n. Pero no es as?; hay anusim y descendientes&#8230;<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[2730,949],"tags":[2764,2882,400,2969,3055,3090,975,358,1960,364,3533,3632,1226],"class_list":["post-282","post","type-post","status-publish","format-standard","hentry","category-articulos-sobre-bnei-anusim","category-bnei-anusim","tag-2764","tag-bet-din","tag-brasil","tag-consejo-de-sabios","tag-estados-unidos","tag-francisco-franco","tag-inquisicion","tag-israel","tag-mexico","tag-portugal","tag-rab-eliahu-birnbaum","tag-reyes-catolicos","tag-espana"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Por doquier: cr?nicas de una traves?a jud - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Por doquier: cr?nicas de una traves?a jud - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"?QUI?NES SON LOS ANUSIM DE NUESTROS D?AS? En t?rminos generales, solemos pensar que los anusim son una especie extinguida, que s?lo se conserva en los libros de historia y los documentos polvorientos de tiempos de la Inquisici?n. Pero no es as?; hay anusim y descendientes...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2011-12-01T15:20:32+00:00\" \/>\n<meta name=\"author\" content=\"beithaanusim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/\"},\"author\":{\"name\":\"beithaanusim\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\"},\"headline\":\"Por doquier: cr?nicas de una traves?a jud\",\"datePublished\":\"2011-12-01T15:20:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/\"},\"wordCount\":2250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"keywords\":[\"2008\",\"Bet Din\",\"Brasil\",\"Consejo de Sabios\",\"Estados Unidos\",\"Francisco Franco\",\"Inquisici\u00f3n\",\"Israel\",\"Mexico\",\"Portugal\",\"Rab Eliahu Birnbaum\",\"Reyes Cat?licos\",\"Spain\"],\"articleSection\":[\"Art?culos sobre Bnei Anusim\",\"Bnei Anusim\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/\",\"name\":\"Por doquier: cr?nicas de una traves?a jud - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"datePublished\":\"2011-12-01T15:20:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2011\\\/12\\\/01\\\/travesiajudia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Por doquier: cr?nicas de una traves?a jud\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\",\"name\":\"beithaanusim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"beithaanusim\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/author\\\/beithaanusim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Por doquier: cr?nicas de una traves?a jud - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/","og_locale":"pt_BR","og_type":"article","og_title":"Por doquier: cr?nicas de una traves?a jud - Shavei Israel","og_description":"?QUI?NES SON LOS ANUSIM DE NUESTROS D?AS? En t?rminos generales, solemos pensar que los anusim son una especie extinguida, que s?lo se conserva en los libros de historia y los documentos polvorientos de tiempos de la Inquisici?n. Pero no es as?; hay anusim y descendientes...","og_url":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/","og_site_name":"Shavei Israel","article_published_time":"2011-12-01T15:20:32+00:00","author":"beithaanusim","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Est. tempo de leitura":"11 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/"},"author":{"name":"beithaanusim","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6"},"headline":"Por doquier: cr?nicas de una traves?a jud","datePublished":"2011-12-01T15:20:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/"},"wordCount":2250,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"keywords":["2008","Bet Din","Brasil","Consejo de Sabios","Estados Unidos","Francisco Franco","Inquisici\u00f3n","Israel","Mexico","Portugal","Rab Eliahu Birnbaum","Reyes Cat?licos","Spain"],"articleSection":["Art?culos sobre Bnei Anusim","Bnei Anusim"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/","url":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/","name":"Por doquier: cr?nicas de una traves?a jud - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"datePublished":"2011-12-01T15:20:32+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2011\/12\/01\/travesiajudia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/"},{"@type":"ListItem","position":2,"name":"Por doquier: cr?nicas de una traves?a jud"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6","name":"beithaanusim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"beithaanusim"},"url":"https:\/\/www.shavei.org\/pt-br\/blog\/author\/beithaanusim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/comments?post=282"}],"version-history":[{"count":0,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/282\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/media?parent=282"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/categories?post=282"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/tags?post=282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}