{"id":2795,"date":"2014-03-13T15:07:43","date_gmt":"2014-03-13T13:07:43","guid":{"rendered":"https:\/\/casa-anusim.org\/?p=2795"},"modified":"2014-03-13T15:07:43","modified_gmt":"2014-03-13T13:07:43","slug":"orgullo-nacional-comentario-a-la-festividad-de-purim","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/","title":{"rendered":"Orgullo Nacional &#8211; Comentario a la Festividad de Purim"},"content":{"rendered":"<p><em>Por Rabino Nissan Ben Avraham<a href=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2014\/03\/51671_13.jpg\"><img decoding=\"async\" class=\"alignright size-medium wp-image-2796\" alt=\"51671_13\" src=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2014\/03\/51671_13.jpg?w=300\" width=\"300\" height=\"190\" \/><\/a><\/em><\/p>\n<p><strong>Cr?ticas por el comportamiento de Mordejai<\/strong><\/p>\n<p>Muchos autores, siguiendo el comportamiento de los jud?os contempor?neos de Mordejai el Jud?o, critican duramente su comportamiento durante la crisis de Ham?n.<\/p>\n<p>Como sabemos, Ham?n hab?a sido ascendido al rango de Primer Ministro en el gobierno del Rey Ajashverosh (Asuero), recibiendo el honor de que todos se arrodillaran a su paso, aunque tal vez este honor ocultaba una medida preventiva, para evitar un atentado contra su persona.<\/p>\n<p>Mordejai se negaba a prosternarse ante el ministro, y al enterarse de ello y de que el transgresor era jud?o, decidi? Ham?n exterminar a todo el Pueblo de Israel.<\/p>\n<p>Los compa?eros de Mordejai le hab?an avisado de que su comportamiento les traer?a grandes desgracias, como efectivamente sucedi?, y por lo tanto le acusaban del desastre que acechaba.<\/p>\n<p>?C?mo hab?a hecho Mordejai una cosa as?, poniendo en peligro no solo a s? mismo, sino a toda su generaci?n y a las que vendr?an despu?s?<!--more--><\/p>\n<p><strong>Mordejai el jud?o<\/strong><\/p>\n<p>Mordejai era un anciano que hab?a sido ya miembro del Gran Tribunal (Sanhedr?n) antes de la destrucci?n del Primer Templo, y hab?a sido uno de los primeros en retornar a su patria y comenzar la reconstrucci?n del Templo, despu?s del Exilio de Babilonia, como podemos ver en el segundo cap?tulo del libro de Ezr? (Esdras 2:2).<\/p>\n<p>En este libro podemos ver c?mo, a continuaci?n, se ven obligados a detener la construcci?n del Templo y de la Ciudad, por orden del rey que hab?a sido mal aconsejado por unos emisarios amalequitas llegados de la Tierra Santa (Esdras 4:5; 4:24).<\/p>\n<p>Para contrarrestar el trabajo de los amalequitas, los reci?n inmigrados env?an a Mordejai al palacio del rey y all? llega a ser miembro del Tribunal persa.<\/p>\n<p><strong>El pecado del pueblo<\/strong><\/p>\n<p>En realidad, deber?amos preguntarnos ?c?mo permiti? el Creador que fuera detenida la reconstrucci?n de Su Templo en Jerusal?n? Est? claro que ha ocurrido algo muy grave que ha despertado el enfado del Creador contra Su pueblo.<\/p>\n<p>La respuesta es sencilla. El pueblo hab?a sido exiliado por su mal comportamiento, llegando a Babilonia. Pero al cabo de setenta a?os de exilio, hab?a llegado al trono el rey Ciro que les hab?a permitido el regreso a su patria y la reconstrucci?n del Templo. Se espera que todos los exiliados se levanten, tomen sus pertenencias y regresen a su patria ancestral. En cambio, el n?mero de los que regresaban era de 42,360 ciudadanos, 7,337 esclavos y 200 cantores.<\/p>\n<p>No tan solo menospreciaban el gran regalo del Creador, que hab?a otorgado una tierra preciosa a su pueblo amado, sino que con ello desment?an la profec?a de Yirmyau (Jerem?as) que hab?a anunciado que al cabo de setenta a?os de exilio podr?an regresar para reconstruir la patria ancestral y el Templo del Creador (cf. Jerem?as 29:10). Tampoco tuvieron en cuenta que el n?mero de los participantes influ?a directamente en el valor de los mandamientos, ya que mientras la mayor?a de los Hijos de Israel no est?n en la Tierra de Israel, el vigor de los mandamientos queda dr?sticamente menguado a un valor simb?lico carente de la santidad que le corresponder?a en caso de estar todos presentes.<\/p>\n<p><strong>?Victoria?<\/strong><\/p>\n<p>Y para colmo, cuando el rey Ajashverosh celebra con un deslumbrante fest?n de medio a?o su ?victoria? sobre el profeta Yirmyau (y sobre el Creador que se lo hab?a anunciado), los jud?os habitantes de la capital Shush?n, no encuentran ?excusas? para no participar en el banquete. ??C?mo pod?an celebrar que Ajashverosh hubiera ?vencido? al Creador?!<\/p>\n<p>Aqu?, dicen los Sabios, hab?an firmado su condena a muerte, su exterminio. Faltaba solo una excusa para ponerlo en pr?ctica.<\/p>\n<p>El pecado hab?a sido m?ltiple: la falta de iniciativa a dejar su bienestar particular en el exilio para reconstruir su patria nacional en ruinas y la falta de orgullo nacional que les permiti? participar en el fest?n de Ajashverosh.<\/p>\n<p><strong>El ant?doto<\/strong><\/p>\n<p>El ant?doto debe ser la restauraci?n de este orgullo nacional, este sentimiento de pertenecer todos al mismo pueblo, un pueblo santo con una misi?n universal.<\/p>\n<p>Al no doblegarse Mordejai ante Ham?n el amalequita, est? inspirando al resto de sus hermanos, que le miran con envidia. Es verdad que al llegar la brutal respuesta de Ham?n muchos de ellos se confunden y ya no saben si alabar o criticar a Mordejai, pero cuando este juez toma las riendas del mando y les ordena participar en un ayuno de tres d?as apoyando espiritualmente a su reina infiltrada en el palacio, todos responden positivamente. Este esfuerzo conjunto es el que consigue dar fuerzas a Ester para anular la siniestra influencia de Ham?n sobre el rey.<\/p>\n<p><strong>Organizando una nueva ali?<\/strong><\/p>\n<p>Adem?s, muchos de ellos, por desgracia no todos, deciden en aqu?l momento reunir sus b?rtulos y prepararse para la Ali?, la inmigraci?n a Israel, aunque tardasen un tiempo en organizarse y llevarla a cabo, como podemos ver en la continuaci?n del libro de Ezr?.<\/p>\n<p>A esto debemos a?adir el valor que tuvieron los que ya hab?an regresado a la Tierra Santa que se atrevieron, animados por los tres profetas Jagai, Zejari? y Malaj? (Ageo, Zacar?as y Malaqu?as), a transgredir las ?rdenes del rey y proseguir la construcci?n del Templo, como podemos ver en los interesantes cap?tulos 5 y 6 del libro de Ezr?.<\/p>\n<p>En la fiesta de Purim celebramos, pues, no tan solo el milagro divino que salv? el pueblo del exterminio perpetrado por el amalequita, sino la restauraci?n, aunque fuera muy parcial y ef?mera, del sentimiento nacional perdido, del orgullo de pertenecer a un pueblo tan especial.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Rabino Nissan Ben Avraham Cr?ticas por el comportamiento de Mordejai Muchos autores, siguiendo el comportamiento de los jud?os contempor?neos de Mordejai el Jud?o, critican duramente su comportamiento durante la crisis de Ham?n. Como sabemos, Ham?n hab?a sido ascendido al rango de Primer Ministro en&#8230;<\/p>\n","protected":false},"author":46,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1],"tags":[2793,396,3058,3071,3139,3401,365,778],"class_list":["post-2795","post","type-post","status-publish","format-standard","hentry","category-uncategorized","tag-ajashverosh","tag-alia","tag-ester","tag-ezra","tag-haman","tag-mordejai","tag-purim","tag-rabino-nissan-ben-avraham"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Orgullo Nacional - Comentario a la Festividad de Purim - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Orgullo Nacional - Comentario a la Festividad de Purim - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"Por Rabino Nissan Ben Avraham Cr?ticas por el comportamiento de Mordejai Muchos autores, siguiendo el comportamiento de los jud?os contempor?neos de Mordejai el Jud?o, critican duramente su comportamiento durante la crisis de Ham?n. Como sabemos, Ham?n hab?a sido ascendido al rango de Primer Ministro en...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2014-03-13T13:07:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2014\/03\/51671_13.jpg?w=300\" \/>\n<meta name=\"author\" content=\"beithaanusim\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/\"},\"author\":{\"name\":\"beithaanusim\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\"},\"headline\":\"Orgullo Nacional &#8211; Comentario a la Festividad de Purim\",\"datePublished\":\"2014-03-13T13:07:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/\"},\"wordCount\":1002,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/51671_13.jpg?w=300\",\"keywords\":[\"Ajashverosh\",\"Alia\",\"Ester\",\"Ezr\",\"Ham\",\"Mordejai\",\"purim\",\"Rabino Nissan Ben Avraham\"],\"articleSection\":[\"Sin categorizar\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/\",\"name\":\"Orgullo Nacional - Comentario a la Festividad de Purim - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/51671_13.jpg?w=300\",\"datePublished\":\"2014-03-13T13:07:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/#primaryimage\",\"url\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/51671_13.jpg?w=300\",\"contentUrl\":\"https:\\\/\\\/healthy-mist.flywheelsites.com\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/51671_13.jpg?w=300\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2014\\\/03\\\/13\\\/orgullo-nacional-comentario-a-la-festividad-de-purim\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Orgullo Nacional &#8211; Comentario a la Festividad de Purim\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/1f0e312c72c93fbeedbcd35f1ccfbcc6\",\"name\":\"beithaanusim\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/?s=96&d=mm&r=g\",\"caption\":\"beithaanusim\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/author\\\/beithaanusim\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Orgullo Nacional - Comentario a la Festividad de Purim - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/","og_locale":"pt_BR","og_type":"article","og_title":"Orgullo Nacional - Comentario a la Festividad de Purim - Shavei Israel","og_description":"Por Rabino Nissan Ben Avraham Cr?ticas por el comportamiento de Mordejai Muchos autores, siguiendo el comportamiento de los jud?os contempor?neos de Mordejai el Jud?o, critican duramente su comportamiento durante la crisis de Ham?n. Como sabemos, Ham?n hab?a sido ascendido al rango de Primer Ministro en...","og_url":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/","og_site_name":"Shavei Israel","article_published_time":"2014-03-13T13:07:43+00:00","og_image":[{"url":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2014\/03\/51671_13.jpg?w=300","type":"","width":"","height":""}],"author":"beithaanusim","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/"},"author":{"name":"beithaanusim","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6"},"headline":"Orgullo Nacional &#8211; Comentario a la Festividad de Purim","datePublished":"2014-03-13T13:07:43+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/"},"wordCount":1002,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/#primaryimage"},"thumbnailUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2014\/03\/51671_13.jpg?w=300","keywords":["Ajashverosh","Alia","Ester","Ezr","Ham","Mordejai","purim","Rabino Nissan Ben Avraham"],"articleSection":["Sin categorizar"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/","url":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/","name":"Orgullo Nacional - Comentario a la Festividad de Purim - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/#primaryimage"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/#primaryimage"},"thumbnailUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2014\/03\/51671_13.jpg?w=300","datePublished":"2014-03-13T13:07:43+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/#primaryimage","url":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2014\/03\/51671_13.jpg?w=300","contentUrl":"https:\/\/healthy-mist.flywheelsites.com\/wp-content\/uploads\/2014\/03\/51671_13.jpg?w=300"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2014\/03\/13\/orgullo-nacional-comentario-a-la-festividad-de-purim\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/"},{"@type":"ListItem","position":2,"name":"Orgullo Nacional &#8211; Comentario a la Festividad de Purim"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/1f0e312c72c93fbeedbcd35f1ccfbcc6","name":"beithaanusim","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/?s=96&d=mm&r=g","caption":"beithaanusim"},"url":"https:\/\/www.shavei.org\/pt-br\/blog\/author\/beithaanusim\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/2795","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/users\/46"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/comments?post=2795"}],"version-history":[{"count":0,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/2795\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/media?parent=2795"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/categories?post=2795"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/tags?post=2795"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}