{"id":137793,"date":"2021-05-27T16:21:20","date_gmt":"2021-05-27T14:21:20","guid":{"rendered":"https:\/\/www.shavei.org\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/"},"modified":"2021-05-27T16:21:20","modified_gmt":"2021-05-27T14:21:20","slug":"a-carta-sobre-a-apostasia","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/","title":{"rendered":"A Carta sobre &#8220;A Apostasia&#8221;"},"content":{"rendered":"<p><!--:en--><strong><span style=\"line-height: 1.5em;\"><img decoding=\"async\" class=\"alignright size-medium wp-image-15993\" src=\"https:\/\/www.shaveiisrael.com\/wp-content\/uploads\/2015\/04\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg\" alt=\"2008_10_18_spain_cordoba_jewish_section_ben_maimonides\" width=\"241\" height=\"300\" \/>O Almohades<\/span><\/strong><\/p>\n<p>A partir da segunda metade do s\u00e9culo 11, da era comum, e durante quase 200 anos, se seguiram, na chamada Andal\u00facia, duas severas dinastias mu\u00e7ulmanas. A primeira foi a dos &#8216;Murabitun&#8217; (almor\u00e1vides &#8211; &#8220;os lutadores&#8221;), que chegaram em Andal\u00facia perto do ano 1086, para impor o verdadeiro Isl\u00e3, que havia sofrido uma mudan\u00e7a pelos mu\u00e7ulmanos que j\u00e1 habitavam a regi\u00e3o. Quando estes se enfraqueceram, ap\u00f3s cerca de um s\u00e9culo, chegaram seus parentes, os &#8216;muwajid\u00fan&#8217; (almohades &#8211; os &#8220;unificadores&#8221; do nome de Al\u00e1), que lutaram para estabelecer novamente o verdadeiro Isl\u00e3.<\/p>\n<p>Estas duas dinastias nasceram no Magrebe, o que hoje conhecemos como Marrocos, mais precisamente nas montanhas do oeste do Atlas, e, lutavam para estabelecer um Isl\u00e3 mais conectado \u00e0s normas que haviam recebido nas grandes escolas de Qairu\u00e1n, Tun\u00edsia e Bagd\u00e1, na Mesopot\u00e2mia. Os &#8216;muwajid\u00fan&#8217; lutaram principalmente contra a corporeidade de Al\u00e1, que consideravam uma heresia para o Isl\u00e3, e, por esta raz\u00e3o, se autodenominaram os &#8220;unificadores&#8221; do nome de D\u00b4us, ou seja, aqueles que estabeleciam a verdadeira teologia isl\u00e2mica, no seu ponto de ver, obviamente.<\/p>\n<p>Ambas as dinastias, que eram conhecidos por suas ferocidades, pela viol\u00eancia e intoler\u00e2ncia, tanto com seus correligion\u00e1rios, quanto com os &#8220;dhimmis&#8221; &#8211; judeus e crist\u00e3os que viviam em suas terras, pagando altos impostos, e, em teoria, eram aceitos pelo Isl\u00e3, por serem anteriores ao Isl\u00e3, e chamados de &#8220;Povos do Livro&#8221;, ou seja, ambos receberam uma vers\u00e3o anterior do Kur\u00e1n, o &#8220;Taura&#8221; (Tor\u00e1) e o &#8220;Ingil&#8221; (Evangelho), respectivamente.<\/p>\n<p>Quando conquistaram o Magrebe, logo em seguida chegaram a Andal\u00facia, e, ent\u00e3o come\u00e7aram a exigir que todos se convertam ao islamismo. Aqueles que puderam, fugiram para outras terras, e aqueles que permaneceram, aparentemente deveriam ter aceitado o Isl\u00e3, embora tenha continuado a existir comunidades crist\u00e3s e judaicas, sob este dom\u00ednio. Curiosamente, parece que, precisamente bem no olho do fura\u00e7\u00e3o, na cidade de Fez, os judeus mantiveram uma certa independ\u00eancia ou, pelo menos, o direito de seguir sua religi\u00e3o.<strong><br \/>\n<\/strong><!--:--><!--more--><!--:en--><\/p>\n<p><strong>A &#8220;Shahada&#8221;<\/strong><\/p>\n<p>De qualquer forma, os judeus questionaram este ser\u00edssimo dilema de como reacionar a esta situa\u00e7\u00e3o que surgiu.<\/p>\n<p>O Talmud diz que a idolatria \u00e9 estritamente proibida, mesmo sob amea\u00e7a iminente de morte. E isto aplica-se, como se sabe, tamb\u00e9m ao cristianismo que \u00e9 considerado idolatria, em todas as suas correntes e seitas, a partir do momento em que aceitam um homem como &#8220;Deus&#8221; ou &#8220;filho&#8221; de deus, mesmo sem praticarem um culto com imagens.<\/p>\n<p>Mas o Isl\u00e3 \u00e9 diferente. Nesta religi\u00e3o n\u00e3o existem outros deuses, n\u00e3o aceitam a divindade de Jesus e n\u00e3o possuem imagens. Todo o necess\u00e1rio para se converter ao islamismo, pelo menos em teoria, \u00e9 a declara\u00e7\u00e3o de &#8220;Testemunho&#8221;, ou &#8220;Shahada&#8221;, em \u00e1rabe, que diz &#8220;N\u00e3o existe outro D&#8217;us sen\u00e3o Al\u00e1, e Maom\u00e9 (Muhammad) \u00e9 seu profeta&#8221;. O D&#8217;us a qual se referem \u00e9 o criador do mundo, sem aditivos ou corantes, (embora uma vers\u00e3o muito primitiva e rasa) assim que esta primeira parte do &#8216;Shahada&#8217; n\u00e3o apresenta nenhum problema. A segunda parte, que consiste em declarar que Muhammad \u00e9 &#8220;o&#8221; profeta, o &#8220;selo&#8221; dos profetas (ou seja, o \u00faltimo e principal), \u00e9 um erro grosseiro, devemos descartar e evitar, mas ainda assim, n\u00e3o se trata de idolatria.<\/p>\n<p>A quest\u00e3o, portanto, era se, fazer esta declara\u00e7\u00e3o consistia em uma transgress\u00e3o que deveria ser negada, mesmo sob amea\u00e7a de morte, ou que sob amea\u00e7a de morte, poderia ser feita. Obviamente que n\u00e3o aceitamos que Muhammad era um profeta, uma vez que nossa no\u00e7\u00e3o de o que era um profeta \u00e9 radicalmente oposta a esta figura, assim como a de Jesus. Mas qual \u00e9 o pecado de fazer esta afirma\u00e7\u00e3o? \u00c9 evidente que o judeu que declara tal coisa, certamente n\u00e3o acredita nisto, e inclusive as for\u00e7as mu\u00e7ulmanas que o for\u00e7avam, tinham conhecimento disso, mas se tratava apenas de uma declara\u00e7\u00e3o da boca para a fora, para salvar a pr\u00f3pria pele. Mas mesmo tal declara\u00e7\u00e3o, do l\u00e1bio para fora, em rela\u00e7\u00e3o a uma idolatria, seria estritamente proibida, sem d\u00favida, como, por exemplo, como o foi com o cristianismo.<br \/>\n<strong>O S\u00e1bio de Fez<\/strong><\/p>\n<p>Nestes tempos surgiu um personagem, provavelmente um rabino, chamado Yehuda Hacohen Ibn Shushan, que criticou duramente os &#8220;Anussim&#8221;, aqueles que aceitaram recitar a Shahada para salvar suas vidas. Na sua opini\u00e3o, perdiam assim seus status de &#8220;judeus&#8221; e tamb\u00e9m suas por\u00e7\u00f5es neste mundo e no mundo vindouro, ap\u00f3s terem contaminado seus l\u00e1bios com tais profana\u00e7\u00f5es. Isto afetava comunidades inteiras, que, aparentemente, n\u00e3o resistiram \u00e0s amea\u00e7as dos muwajid\u00fan e tiveram que recitar a Shahada. Os judeus que j\u00e1 tinham recitado a Shahada, acreditavam que, seguindo a opini\u00e3o deste s\u00e1bio, n\u00e3o tinham mais a necessidade de se comprometer com os mandamentos da Tor\u00e1 em segredo e, assim, efetivamente desapareceram como judeus.<\/p>\n<p>J\u00e1 Maim\u00f4nides n\u00e3o concordava com esta vis\u00e3o e criticou com palavras duras o s\u00e1bio de Fez, apresentando v\u00e1rias provas contra a sua opini\u00e3o.<br \/>\n<strong>Fundamentos em Defesa<\/strong><\/p>\n<p>Primeiro est\u00e1 a grave proibi\u00e7\u00e3o de falar mal das comunidades judaicas, mesmo estas que tinham recitado a Shahada. Cita, por exemplo, o caso dos filhos de Israel nos tempos do profeta Eliyahu (Elias), que eram id\u00f3latras em sua maioria, e quando ele falou mal destes, o Criador lhe castigou severamente.<\/p>\n<p>Ele tamb\u00e9m cita a hist\u00f3ria do Talmud, quando o Rabino Meir, se faz passar por um n\u00e3o-judeu para salvar sua vida, inclusive mergulhando o dedo em um caldo de carne de porco, chupando outro dedo, em seguida, para fazer os inimigos acreditarem que ele havia comido do caldo, e outro deles, o Rabino Eliezer o Grande, do qual o Midrash (Kohelet Rab\u00e1) afirma que cometeu apostasia.<\/p>\n<p>Maim\u00f4nides explica que a pessoa sempre pode consertar, especialmente quando a atitude foi tomada em uma posi\u00e7\u00e3o de coer\u00e7\u00e3o completa. Uma pessoa que tenha cometido idolatria sob coa\u00e7\u00e3o, embora devesse ter preferido a morte, n\u00e3o recebe qualquer puni\u00e7\u00e3o, seja neste mundo ou no pr\u00f3ximo, caso n\u00e3o o tenha feito. E, portanto, deve continuar a esfor\u00e7ar-se para cumprir quantos mais comandos puder, em segredo, esperando a oportunidade de poder escapar para outros lugares, onde possa retomar sua vida religiosa.<\/p>\n<p><strong>1391<\/strong><\/p>\n<p>Alguns s\u00e9culos mais tarde, em 1391, quando a coer\u00e7\u00e3o aconteceu em Castela e Arag\u00e3o, por parte dos crist\u00e3os, dois rabinos citaram esta carta de Maim\u00f4nides. Foram estes o Rivash (Rabi Yitschac bar Cesat Perfet, de Valencia) e seu aluno Rashbats (Rabi Shimon ben Tsemach Duran, de Mallorca), que escreveram suas respostas no que diz respeito aos Anussim, citando Maim\u00f4nides, a primeira na resposta 11 e a segunda nas respostas 60 e 61.<\/p>\n<p>Neste sentido, sem d\u00favida, se tratava de um problema de idolatria, mas, mesmo assim, estes dois rabinos sa\u00edram em defesa dos Anussim, afirmando que estes n\u00e3o deixaram de ser judeus por terem cometido idolatria, mesmo que deveriam ter preferido a morte, acrescentando que, por muitos anos e mesmo s\u00e9culos, continuaram sendo judeus, ainda obrigados a cumprir toda a Tor\u00e1, assim como seus antepassados.<\/p>\n<p>Apesar de tudo isso, em seu livro de Leis &#8220;Mishne Tor\u00e1&#8221;, Maim\u00f4nides afirma que aquele que escolher permanecer nestes lugares onde os judeus s\u00e3o for\u00e7ados a transgredir os mandamentos da Tor\u00e1, \u00e9 considerado pior que um &#8220;c\u00e3o que chafurda no v\u00f4mito&#8221;, e deve fazer todo o poss\u00edvel para escapar desta terra in\u00f3spita e buscar viver num lugar onde poder\u00e1 praticar livremente os mandamentos divinos.<\/p>\n<p>A &#8220;Carta de Apostasia&#8221;, ou a &#8220;Carta da Santifica\u00e7\u00e3o do Nome Divino&#8221; \u00e9 um dos textos mais importantes para a compreens\u00e3o da quest\u00e3o da coer\u00e7\u00e3o e dos Anussim, e a\u00ed est\u00e1 a base de tudo aquilo que devemos saber sobre o assunto.<!--:--><!--:es--><\/p>\n<p><!--:--><\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Almohades A partir da segunda metade do s\u00e9culo 11, da era comum, e durante quase 200 anos, se seguiram, na chamada Andal\u00facia, duas severas dinastias mu\u00e7ulmanas. A primeira foi a dos &#8216;Murabitun&#8217; (almor\u00e1vides &#8211; &#8220;os lutadores&#8221;), que chegaram em Andal\u00facia perto do ano 1086,&#8230;<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[6932],"tags":[6933],"class_list":["post-137793","post","type-post","status-publish","format-standard","hentry","category-judaismoartigosjudaismohistoria-do-povo-judeu","tag-historia-judaicajudaismojuderias"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>A Carta sobre &quot;A Apostasia&quot; - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A Carta sobre &quot;A Apostasia&quot; - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"O Almohades A partir da segunda metade do s\u00e9culo 11, da era comum, e durante quase 200 anos, se seguiram, na chamada Andal\u00facia, duas severas dinastias mu\u00e7ulmanas. A primeira foi a dos &#8216;Murabitun&#8217; (almor\u00e1vides &#8211; &#8220;os lutadores&#8221;), que chegaram em Andal\u00facia perto do ano 1086,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-27T14:21:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.shaveiisrael.com\/wp-content\/uploads\/2015\/04\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg\" \/>\n<meta name=\"author\" content=\"daniella\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/\"},\"author\":{\"name\":\"daniella\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/628be1364b127546c700d93458cf9e4c\"},\"headline\":\"A Carta sobre &#8220;A Apostasia&#8221;\",\"datePublished\":\"2021-05-27T14:21:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/\"},\"wordCount\":1345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.shaveiisrael.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg\",\"keywords\":[\"historia judaica|juda\u00edsmo|Juder\u00edas\"],\"articleSection\":[\"JUDA\u00cdSMO&gt;Artigos|JUDA\u00cdSMO&gt;Hist\u00f3ria do Povo Judeu\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/\",\"name\":\"A Carta sobre \\\"A Apostasia\\\" - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.shaveiisrael.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg\",\"datePublished\":\"2021-05-27T14:21:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.shaveiisrael.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shaveiisrael.com\\\/wp-content\\\/uploads\\\/2015\\\/04\\\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2021\\\/05\\\/27\\\/a-carta-sobre-a-apostasia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A Carta sobre &#8220;A Apostasia&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/628be1364b127546c700d93458cf9e4c\",\"name\":\"daniella\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g\",\"caption\":\"daniella\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/author\\\/daniella\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A Carta sobre \"A Apostasia\" - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/","og_locale":"pt_BR","og_type":"article","og_title":"A Carta sobre \"A Apostasia\" - Shavei Israel","og_description":"O Almohades A partir da segunda metade do s\u00e9culo 11, da era comum, e durante quase 200 anos, se seguiram, na chamada Andal\u00facia, duas severas dinastias mu\u00e7ulmanas. A primeira foi a dos &#8216;Murabitun&#8217; (almor\u00e1vides &#8211; &#8220;os lutadores&#8221;), que chegaram em Andal\u00facia perto do ano 1086,...","og_url":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/","og_site_name":"Shavei Israel","article_published_time":"2021-05-27T14:21:20+00:00","og_image":[{"url":"https:\/\/www.shaveiisrael.com\/wp-content\/uploads\/2015\/04\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg","type":"","width":"","height":""}],"author":"daniella","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Est. tempo de leitura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/"},"author":{"name":"daniella","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/628be1364b127546c700d93458cf9e4c"},"headline":"A Carta sobre &#8220;A Apostasia&#8221;","datePublished":"2021-05-27T14:21:20+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/"},"wordCount":1345,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shaveiisrael.com\/wp-content\/uploads\/2015\/04\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg","keywords":["historia judaica|juda\u00edsmo|Juder\u00edas"],"articleSection":["JUDA\u00cdSMO&gt;Artigos|JUDA\u00cdSMO&gt;Hist\u00f3ria do Povo Judeu"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/","url":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/","name":"A Carta sobre \"A Apostasia\" - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/#primaryimage"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shaveiisrael.com\/wp-content\/uploads\/2015\/04\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg","datePublished":"2021-05-27T14:21:20+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/#primaryimage","url":"https:\/\/www.shaveiisrael.com\/wp-content\/uploads\/2015\/04\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg","contentUrl":"https:\/\/www.shaveiisrael.com\/wp-content\/uploads\/2015\/04\/2008_10_18_spain_cordoba_jewish_section_ben_maimonides-241x300.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2021\/05\/27\/a-carta-sobre-a-apostasia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/"},{"@type":"ListItem","position":2,"name":"A Carta sobre &#8220;A Apostasia&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/628be1364b127546c700d93458cf9e4c","name":"daniella","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bf8b97193609e61ba4fd9bacc2cb0ef6ed3fbf5eb2df25350c1e263020233ff8?s=96&d=mm&r=g","caption":"daniella"},"url":"https:\/\/www.shavei.org\/pt-br\/blog\/author\/daniella\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/137793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/comments?post=137793"}],"version-history":[{"count":0,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/137793\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/media?parent=137793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/categories?post=137793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/tags?post=137793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}