{"id":104104,"date":"2019-09-13T07:36:10","date_gmt":"2019-09-13T05:36:10","guid":{"rendered":"https:\/\/www.shavei.org\/o-comeco-das-selichot\/"},"modified":"2019-09-13T07:41:31","modified_gmt":"2019-09-13T05:41:31","slug":"o-comeco-das-selichot","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/","title":{"rendered":"O come\u00e7o das Selichot"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">\u00c0 medida que as festas judaicas se aproximam, segue-se uma tradi\u00e7\u00e3o especial de recitar Selichot (ora\u00e7\u00f5es comunit\u00e1rias pelo perd\u00e3o divino). As Selichot s\u00e3o recitadas todos os dias at\u00e9 o final das Altas Festas, que come\u00e7am com Rosh Hashana e terminam com Yom Kipur, o Dia do Perd\u00e3o. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O costume sefardita \u00e9 come\u00e7ar um m\u00eas antes do in\u00edcio das festas, enquanto a tradi\u00e7\u00e3o Ashkenazi \u00e9 come\u00e7ar apenas na noite de s\u00e1bado antes de Rosh Hashana. Os Bnei Menashe, que geralmente seguem os costumes sefarditas, acordaram de manh\u00e3 cedo para recitar Selichot, que consistem em ora\u00e7\u00f5es e poemas especiais, enquanto se preparam para as festas de fim de ano e pedem perd\u00e3o a D&#8217;us. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As fotos s\u00e3o o come\u00e7o das Slichot no Mercaz Shavei Israel, em Aizawl, Mizoram, no nordeste da \u00cdndia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Selichot em Manipur.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"> (foto de: Meital Singson)<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-2 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2-1024x768.jpeg\" alt=\"\" data-id=\"103486\" data-link=\"https:\/\/www.shavei.org\/?attachment_id=103486\" class=\"wp-image-103486\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2-1024x768.jpeg 1024w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2-300x225.jpeg 300w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2-800x600.jpeg 800w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2-700x525.jpeg 700w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2.jpeg 1280w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot1-768x1024.jpeg\" alt=\"\" data-id=\"103478\" data-link=\"https:\/\/www.shavei.org\/?attachment_id=103478\" class=\"wp-image-103478\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot1-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot1-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot1-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot1-700x933.jpeg 700w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot1.jpeg 780w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/figure><\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Selichot in Manipur<\/strong> (Credit: Meital Singson)<\/p>\n\n\n\n<ul class=\"wp-block-gallery columns-4 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/i0.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.10.jpeg?fit=1024%2C768&amp;ssl=1\" alt=\"\" data-id=\"103716\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-10\/\" class=\"wp-image-103716\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.10.jpeg 1280w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.10-300x225.jpeg 300w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.10-1024x768.jpeg 1024w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.10-800x600.jpeg 800w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.10-700x525.jpeg 700w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/i0.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.111.jpeg?fit=768%2C1024&amp;ssl=1\" alt=\"\" data-id=\"103724\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-111\/\" class=\"wp-image-103724\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.111.jpeg 960w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.111-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.111-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.111-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.111-700x933.jpeg 700w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/i2.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.11.jpeg?fit=768%2C1024&amp;ssl=1\" alt=\"\" data-id=\"103732\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-11\/\" class=\"wp-image-103732\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.11.jpeg 960w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.11-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.11-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.11-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.11-700x933.jpeg 700w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/i0.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.12.jpeg?fit=768%2C1024&amp;ssl=1\" alt=\"\" data-id=\"103740\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-12\/\" class=\"wp-image-103740\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.12.jpeg 960w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.12-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.12-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.12-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.12-700x933.jpeg 700w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/i1.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.13.jpeg?fit=768%2C1024&amp;ssl=1\" alt=\"\" data-id=\"103748\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-13\/\" class=\"wp-image-103748\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.13.jpeg 960w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.13-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.13-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.13-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.13-700x933.jpeg 700w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/i0.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.14.jpeg?fit=1024%2C768&amp;ssl=1\" alt=\"\" data-id=\"103756\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-14\/\" class=\"wp-image-103756\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.14.jpeg 1280w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.14-300x225.jpeg 300w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.14-1024x768.jpeg 1024w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.14-800x600.jpeg 800w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.14-700x525.jpeg 700w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/i2.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.15.jpeg?fit=768%2C1024&amp;ssl=1\" alt=\"\" data-id=\"103765\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-15\/\" class=\"wp-image-103765\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.15.jpeg 960w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.15-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.15-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.15-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.15-700x933.jpeg 700w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"1280\" height=\"960\" src=\"https:\/\/i1.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.16.jpeg?fit=1024%2C768&amp;ssl=1\" alt=\"\" data-id=\"103773\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-16\/\" class=\"wp-image-103773\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.16.jpeg 1280w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.16-300x225.jpeg 300w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.16-1024x768.jpeg 1024w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.16-800x600.jpeg 800w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.16-700x525.jpeg 700w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/i2.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.27.jpeg?fit=768%2C1024&amp;ssl=1\" alt=\"\" data-id=\"103781\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-27\/\" class=\"wp-image-103781\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.27.jpeg 960w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.27-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.27-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.27-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.27-700x933.jpeg 700w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/i2.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.301.jpeg?fit=768%2C1024&amp;ssl=1\" alt=\"\" data-id=\"103789\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-301\/\" class=\"wp-image-103789\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.301.jpeg 960w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.301-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.301-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.301-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.301-700x933.jpeg 700w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"960\" height=\"1280\" src=\"https:\/\/i1.wp.com\/fluttering-quail.flywheelsites.com\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.30.jpeg?fit=768%2C1024&amp;ssl=1\" alt=\"\" data-id=\"103797\" data-link=\"https:\/\/www.shavei.org\/start-of-selichot\/whatsapp-image-2019-09-05-at-14-56-30\/\" class=\"wp-image-103797\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.30.jpeg 960w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.30-225x300.jpeg 225w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.30-768x1024.jpeg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.30-600x800.jpeg 600w, https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/WhatsApp-Image-2019-09-05-at-14.56.30-700x933.jpeg 700w\" sizes=\"(max-width: 960px) 100vw, 960px\" \/><\/figure><\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>\u00c0 medida que as festas judaicas se aproximam, segue-se uma tradi\u00e7\u00e3o especial de recitar Selichot (ora\u00e7\u00f5es comunit\u00e1rias pelo perd\u00e3o divino). As Selichot s\u00e3o recitadas todos os dias at\u00e9 o final das Altas Festas, que come\u00e7am com Rosh Hashana e terminam com Yom Kipur, o Dia&#8230;<\/p>\n","protected":false},"author":7,"featured_media":103490,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1899,1855],"tags":[294,2010,2009],"class_list":["post-104104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bnei-menashe-pt-br","category-sin-categorizar-pt-br","tag-bnei-menashe","tag-festividades-judias","tag-selijot"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>O come\u00e7o das Selichot - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"O come\u00e7o das Selichot - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"\u00c0 medida que as festas judaicas se aproximam, segue-se uma tradi\u00e7\u00e3o especial de recitar Selichot (ora\u00e7\u00f5es comunit\u00e1rias pelo perd\u00e3o divino). As Selichot s\u00e3o recitadas todos os dias at\u00e9 o final das Altas Festas, que come\u00e7am com Rosh Hashana e terminam com Yom Kipur, o Dia...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-13T05:36:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-09-13T05:41:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Ben-David\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/\"},\"author\":{\"name\":\"Laura Ben-David\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/00b45bee9f161469e8b81745e0fad63f\"},\"headline\":\"O come\u00e7o das Selichot\",\"datePublished\":\"2019-09-13T05:36:10+00:00\",\"dateModified\":\"2019-09-13T05:41:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/\"},\"wordCount\":163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/selichot2.jpeg\",\"keywords\":[\"Bnei Menashe\",\"Festividades Jud\u00edas\",\"Selijot\"],\"articleSection\":[\"Bnei Menashe\",\"Sin categorizar\"],\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/\",\"name\":\"O come\u00e7o das Selichot - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/selichot2.jpeg\",\"datePublished\":\"2019-09-13T05:36:10+00:00\",\"dateModified\":\"2019-09-13T05:41:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/selichot2.jpeg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/selichot2.jpeg\",\"width\":1280,\"height\":960},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/2019\\\/09\\\/13\\\/o-comeco-das-selichot\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"O come\u00e7o das Selichot\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/00b45bee9f161469e8b81745e0fad63f\",\"name\":\"Laura Ben-David\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0939c5754a1cd2ebff55eeefe7aae273ff8235a123cddb1b328a230fc69d6323?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0939c5754a1cd2ebff55eeefe7aae273ff8235a123cddb1b328a230fc69d6323?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/0939c5754a1cd2ebff55eeefe7aae273ff8235a123cddb1b328a230fc69d6323?s=96&d=mm&r=g\",\"caption\":\"Laura Ben-David\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/pt-br\\\/blog\\\/author\\\/laurabd\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"O come\u00e7o das Selichot - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/","og_locale":"pt_BR","og_type":"article","og_title":"O come\u00e7o das Selichot - Shavei Israel","og_description":"\u00c0 medida que as festas judaicas se aproximam, segue-se uma tradi\u00e7\u00e3o especial de recitar Selichot (ora\u00e7\u00f5es comunit\u00e1rias pelo perd\u00e3o divino). As Selichot s\u00e3o recitadas todos os dias at\u00e9 o final das Altas Festas, que come\u00e7am com Rosh Hashana e terminam com Yom Kipur, o Dia...","og_url":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/","og_site_name":"Shavei Israel","article_published_time":"2019-09-13T05:36:10+00:00","article_modified_time":"2019-09-13T05:41:31+00:00","og_image":[{"width":1280,"height":960,"url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2.jpeg","type":"image\/jpeg"}],"author":"Laura Ben-David","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/"},"author":{"name":"Laura Ben-David","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/00b45bee9f161469e8b81745e0fad63f"},"headline":"O come\u00e7o das Selichot","datePublished":"2019-09-13T05:36:10+00:00","dateModified":"2019-09-13T05:41:31+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/"},"wordCount":163,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2.jpeg","keywords":["Bnei Menashe","Festividades Jud\u00edas","Selijot"],"articleSection":["Bnei Menashe","Sin categorizar"],"inLanguage":"pt-BR","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/","url":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/","name":"O come\u00e7o das Selichot - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/#primaryimage"},"image":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2.jpeg","datePublished":"2019-09-13T05:36:10+00:00","dateModified":"2019-09-13T05:41:31+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/#primaryimage","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2.jpeg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2019\/09\/selichot2.jpeg","width":1280,"height":960},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/pt-br\/blog\/2019\/09\/13\/o-comeco-das-selichot\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/"},{"@type":"ListItem","position":2,"name":"O come\u00e7o das Selichot"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/00b45bee9f161469e8b81745e0fad63f","name":"Laura Ben-David","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/secure.gravatar.com\/avatar\/0939c5754a1cd2ebff55eeefe7aae273ff8235a123cddb1b328a230fc69d6323?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/0939c5754a1cd2ebff55eeefe7aae273ff8235a123cddb1b328a230fc69d6323?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/0939c5754a1cd2ebff55eeefe7aae273ff8235a123cddb1b328a230fc69d6323?s=96&d=mm&r=g","caption":"Laura Ben-David"},"url":"https:\/\/www.shavei.org\/pt-br\/blog\/author\/laurabd\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/104104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/comments?post=104104"}],"version-history":[{"count":2,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/104104\/revisions"}],"predecessor-version":[{"id":104106,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/posts\/104104\/revisions\/104106"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/media\/103490"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/media?parent=104104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/categories?post=104104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/pt-br\/wp-json\/wp\/v2\/tags?post=104104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}