{"id":1765,"count":1,"description":"","link":"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/","name":"Rav Yejiel Chilewski","slug":"rav-yejiel-chilewski-he","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Rav Yejiel Chilewski Archives - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/\" \/>\n<meta property=\"og:locale\" content=\"he_IL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rav Yejiel Chilewski Archives - Shavei Israel\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/he\\\/blog\\\/tag\\\/rav-yejiel-chilewski-he\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/he\\\/blog\\\/tag\\\/rav-yejiel-chilewski-he\\\/\",\"name\":\"Rav Yejiel Chilewski Archives - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/he\\\/blog\\\/tag\\\/rav-yejiel-chilewski-he\\\/#breadcrumb\"},\"inLanguage\":\"he-IL\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/he\\\/blog\\\/tag\\\/rav-yejiel-chilewski-he\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/he\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rav Yejiel Chilewski\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"he-IL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"he-IL\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Rav Yejiel Chilewski Archives - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/","og_locale":"he_IL","og_type":"article","og_title":"Rav Yejiel Chilewski Archives - Shavei Israel","og_url":"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/","og_site_name":"Shavei Israel","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/","url":"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/","name":"Rav Yejiel Chilewski Archives - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"breadcrumb":{"@id":"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/#breadcrumb"},"inLanguage":"he-IL"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/he\/blog\/tag\/rav-yejiel-chilewski-he\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/he\/"},{"@type":"ListItem","position":2,"name":"Rav Yejiel Chilewski"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"he-IL"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"he-IL","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/he\/wp-json\/wp\/v2\/tags\/1765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/he\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.shavei.org\/he\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.shavei.org\/he\/wp-json\/wp\/v2\/posts?tags=1765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}