{"id":26353,"date":"2016-02-15T12:24:55","date_gmt":"2016-02-15T12:24:55","guid":{"rendered":"https:\/\/www.shavei.org\/es\/?p=26353"},"modified":"2017-06-04T12:07:55","modified_gmt":"2017-06-04T10:07:55","slug":"campana-kaifeng-conozca-a-li-jing","status":"publish","type":"post","link":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/","title":{"rendered":"CAMPA\u00d1A KAIFENG: conozca a Li Jing"},"content":{"rendered":"<p><em>Por Brian Blum<\/em><\/p>\n<p><a href=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport.jpg\" rel=\"attachment wp-att-25292\"><img decoding=\"async\" class=\"size-medium wp-image-25292\" src=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-300x225.jpg\" alt=\"Li Jing with her passport\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-300x225.jpg 300w, https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-768x576.jpg 768w, https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-1024x768.jpg 1024w, https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-800x600.jpg 800w, https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-700x525.jpg 700w, https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-167x125.jpg 167w, https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-292x219.jpg 292w, https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport-528x396.jpg 528w, https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing-with-passport.jpg 1280w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La ali\u00e1 de China contin\u00faa. En los pr\u00f3ximos meses, cinco j\u00f3venes mujeres de la comunidad jud\u00eda de Kaifeng, emigrar\u00e1n a Israel. Cada una tiene su propia y fascinante historia. Por favor conozca a Li Jing.<\/p>\n<p>A los 27 a\u00f1os de edad, Li Jing es la mayor de las cinco mujeres. Li creci\u00f3 en Kaifeng, pero estudi\u00f3 ingl\u00e9s de negocios en la universidad en Xi&#8217;an, a seis horas de tren de su ciudad natal y el hogar de los famosos guerreros de terracota.<\/p>\n<p>Despu\u00e9s de sus estudios, Li trabaj\u00f3 como gerente de servicio al cliente en Kaifeng hasta hace dos meses, cuando dej\u00f3 su trabajo para comenzar a preparar con mayor intensidad su ali\u00e1. \u00abMe gustaba mucho mi trabajo\u00bb, dice ella. Sin embargo, est\u00e1 lista para nuevas oportunidades de negocio en Israel. En estos d\u00edas, est\u00e1 estudiando hebreo e ingl\u00e9s en l\u00ednea con un tutor especial de Shavei Israel.<\/p>\n<p>A diferencia de algunas otras comunidades con las que Shavei Israel trabaja, los Jud\u00edos de Kaifeng nunca olvidaron u ocultaron su identidad jud\u00eda. \u00abHe sabido desde peque\u00f1a que soy jud\u00eda\u00bb, dice Li Jing. \u00abMi padre nos dijo que nuestros antepasados vinieron de Israel. Aun as\u00ed, s\u00e9 que tengo un mont\u00f3n de cosas por aprender. Cuando mi padre me cont\u00f3 por primera vez sobre nuestros antepasados, me llen\u00e9 de orgullo. Pero luego qued\u00e9 un poco desconcertada. Quiero decir, \u00bfqu\u00e9 significa ser jud\u00eda?\u00bb.<\/p>\n<p>Cuando Li creci\u00f3, sus padres hicieron todo lo posible para ense\u00f1arle lo que significa ser jud\u00eda. \u00abHemos mantenido el s\u00e1bado, celebramos el A\u00f1o Nuevo y todos los d\u00edas de fiesta -Yom Kipur, Sucot, Januc\u00e1, Pascua &#8211; seg\u00fan la ley jud\u00eda\u00bb, dice ella. \u00abHacemos Kidush [santificaci\u00f3n del vino] en Shabat y dem\u00e1s festividades\u00bb. La familia de Li ha sido activa en la comunidad jud\u00eda de Kaifeng, participando en las celebraciones y actividades del grupo.<!--more--><\/p>\n<p>Li tiene amigos fuera de la comunidad jud\u00eda, por supuesto. \u00abPero yo s\u00f3lo como alimentos que son kosher\u00bb, dice ella. \u00abTodos mis amigos respetan eso\u00bb.<\/p>\n<p>Li dice que una de sus grandes pasiones es viajar &#8211; y ella pronto podr\u00e1 cumplirlo cuando se diriga a Israel. La recepci\u00f3n de la carta de Shavei Israel, en la que se le informaba a Li que estar\u00eda haciendo ali\u00e1 \u00abfue el momento m\u00e1s feliz de mi vida\u00bb, dice ella. \u00abYo hab\u00eda estado esperando durante m\u00e1s de seis a\u00f1os, desde que los siete hombres llegaron a Israel\u00bb (Li se refiere a los siete j\u00f3venes chinos a quienes Shavei Israel ayud\u00f3 a realizar ali\u00e1 en el 2009).<\/p>\n<p>Shavei Israel ha sido una gran parte de la vida de Li. \u00abHan enviado libros y maestros a nuestra comunidad\u00bb, dice ella. Todo esto ha ayudado a Li a prepararse para el gran d\u00eda. \u00abSi hay alguna lecci\u00f3n de vida que he aprendido, es de apreciar todo lo que tengo &#8211; mi familia y mis amigos. \u00a1Y esa oportunidad se da a aquellos que se han preparado!\u00bb<\/p>\n<p>Y si bien la oportunidad actual es para Li, est\u00e1 segura de que su ali\u00e1 tendr\u00e1 un impacto en sus compa\u00f1eros jud\u00edos de Kaifeng. \u00abEspero que pueda dar algo a cambio a mi comunidad, para que sea cada vez mejor\u00bb.<\/p>\n<p>Por ahora, hay que aprender m\u00e1s hebreo &#8211; ahora en Kaifeng y luego en Jerusal\u00e9n. \u00abS\u00e9 que el aprendizaje de la lengua ser\u00e1 un obst\u00e1culo. Pero siempre trato de ser optimista en todo lo que hago\u00bb.<br \/>\nCon una actitud tan positiva, no hay duda de que Li Jing tendr\u00e1 \u00e9xito en la tierra de sus antepasados.<\/p>\n<p>Para obtener m\u00e1s informaci\u00f3n acerca de la \u00abCampa\u00f1a Kaifeng\u00bb de Shavei Israel y c\u00f3mo puede hacer una diferencia real con su donaci\u00f3n, por favor visite nuestra p\u00e1gina de donaciones. Y vea este sitio para m\u00e1s perfiles de los nuevos inmigrantes de la Tierra del Drag\u00f3n Rojo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por Brian Blum La ali\u00e1 de China contin\u00faa. En los pr\u00f3ximos meses, cinco j\u00f3venes mujeres de la comunidad jud\u00eda de Kaifeng, emigrar\u00e1n a Israel. Cada una tiene su propia y fascinante historia. Por favor conozca a Li Jing. A los 27 a\u00f1os de edad, Li&#8230;<\/p>\n","protected":false},"author":8,"featured_media":25290,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"give_campaign_id":0,"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0,"ngg_post_thumbnail":0,"footnotes":""},"categories":[1114,504],"tags":[],"class_list":["post-26353","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-historias-personales","category-judios-kaifeng"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>CAMPA\u00d1A KAIFENG: conozca a Li Jing - Shavei Israel<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"CAMPA\u00d1A KAIFENG: conozca a Li Jing - Shavei Israel\" \/>\n<meta property=\"og:description\" content=\"Por Brian Blum La ali\u00e1 de China contin\u00faa. En los pr\u00f3ximos meses, cinco j\u00f3venes mujeres de la comunidad jud\u00eda de Kaifeng, emigrar\u00e1n a Israel. Cada una tiene su propia y fascinante historia. Por favor conozca a Li Jing. A los 27 a\u00f1os de edad, Li...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/\" \/>\n<meta property=\"og:site_name\" content=\"Shavei Israel\" \/>\n<meta property=\"article:published_time\" content=\"2016-02-15T12:24:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-04T10:07:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2000\" \/>\n\t<meta property=\"og:image:height\" content=\"1333\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Shavei Israel\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/\"},\"author\":{\"name\":\"Shavei Israel\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/be34c059c9b16cdd461eed6c3ee0cf22\"},\"headline\":\"CAMPA\u00d1A KAIFENG: conozca a Li Jing\",\"datePublished\":\"2016-02-15T12:24:55+00:00\",\"dateModified\":\"2017-06-04T10:07:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/\"},\"wordCount\":683,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Li-Jing.jpg\",\"articleSection\":[\"Historias Personales\",\"Jud\u00edos de Kaifeng\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/\",\"name\":\"CAMPA\u00d1A KAIFENG: conozca a Li Jing - Shavei Israel\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Li-Jing.jpg\",\"datePublished\":\"2016-02-15T12:24:55+00:00\",\"dateModified\":\"2017-06-04T10:07:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Li-Jing.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2016\\\/01\\\/Li-Jing.jpg\",\"width\":2000,\"height\":1333,\"caption\":\"Li Jing in Kaifeng\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/2016\\\/02\\\/15\\\/campana-kaifeng-conozca-a-li-jing\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"CAMPA\u00d1A KAIFENG: conozca a Li Jing\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#website\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"name\":\"Shavei Israel\",\"description\":\"One nation, many faces. We help them all return.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.shavei.org\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#organization\",\"name\":\"Shavei Israel\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.shavei.org\\\/wp-content\\\/uploads\\\/2017\\\/10\\\/shavei-logo.jpg\",\"width\":300,\"height\":285,\"caption\":\"Shavei Israel\"},\"image\":{\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.shavei.org\\\/#\\\/schema\\\/person\\\/be34c059c9b16cdd461eed6c3ee0cf22\",\"name\":\"Shavei Israel\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df74477975a50f1c87a7dace91f34be8bb2637b8220dd744eaf5ef9922e052e?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df74477975a50f1c87a7dace91f34be8bb2637b8220dd744eaf5ef9922e052e?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3df74477975a50f1c87a7dace91f34be8bb2637b8220dd744eaf5ef9922e052e?s=96&d=mm&r=g\",\"caption\":\"Shavei Israel\"},\"url\":\"https:\\\/\\\/www.shavei.org\\\/es\\\/blog\\\/author\\\/shaveiisrael\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"CAMPA\u00d1A KAIFENG: conozca a Li Jing - Shavei Israel","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/","og_locale":"es_ES","og_type":"article","og_title":"CAMPA\u00d1A KAIFENG: conozca a Li Jing - Shavei Israel","og_description":"Por Brian Blum La ali\u00e1 de China contin\u00faa. En los pr\u00f3ximos meses, cinco j\u00f3venes mujeres de la comunidad jud\u00eda de Kaifeng, emigrar\u00e1n a Israel. Cada una tiene su propia y fascinante historia. Por favor conozca a Li Jing. A los 27 a\u00f1os de edad, Li...","og_url":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/","og_site_name":"Shavei Israel","article_published_time":"2016-02-15T12:24:55+00:00","article_modified_time":"2017-06-04T10:07:55+00:00","og_image":[{"width":2000,"height":1333,"url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing.jpg","type":"image\/jpeg"}],"author":"Shavei Israel","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":false,"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/#article","isPartOf":{"@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/"},"author":{"name":"Shavei Israel","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/be34c059c9b16cdd461eed6c3ee0cf22"},"headline":"CAMPA\u00d1A KAIFENG: conozca a Li Jing","datePublished":"2016-02-15T12:24:55+00:00","dateModified":"2017-06-04T10:07:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/"},"wordCount":683,"commentCount":0,"publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"image":{"@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing.jpg","articleSection":["Historias Personales","Jud\u00edos de Kaifeng"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/","url":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/","name":"CAMPA\u00d1A KAIFENG: conozca a Li Jing - Shavei Israel","isPartOf":{"@id":"https:\/\/www.shavei.org\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/#primaryimage"},"image":{"@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/#primaryimage"},"thumbnailUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing.jpg","datePublished":"2016-02-15T12:24:55+00:00","dateModified":"2017-06-04T10:07:55+00:00","breadcrumb":{"@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/#primaryimage","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2016\/01\/Li-Jing.jpg","width":2000,"height":1333,"caption":"Li Jing in Kaifeng"},{"@type":"BreadcrumbList","@id":"https:\/\/www.shavei.org\/es\/blog\/2016\/02\/15\/campana-kaifeng-conozca-a-li-jing\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.shavei.org\/es\/"},{"@type":"ListItem","position":2,"name":"CAMPA\u00d1A KAIFENG: conozca a Li Jing"}]},{"@type":"WebSite","@id":"https:\/\/www.shavei.org\/#website","url":"https:\/\/www.shavei.org\/","name":"Shavei Israel","description":"One nation, many faces. We help them all return.","publisher":{"@id":"https:\/\/www.shavei.org\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.shavei.org\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.shavei.org\/#organization","name":"Shavei Israel","url":"https:\/\/www.shavei.org\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/","url":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","contentUrl":"https:\/\/www.shavei.org\/wp-content\/uploads\/2017\/10\/shavei-logo.jpg","width":300,"height":285,"caption":"Shavei Israel"},"image":{"@id":"https:\/\/www.shavei.org\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.shavei.org\/#\/schema\/person\/be34c059c9b16cdd461eed6c3ee0cf22","name":"Shavei Israel","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/3df74477975a50f1c87a7dace91f34be8bb2637b8220dd744eaf5ef9922e052e?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3df74477975a50f1c87a7dace91f34be8bb2637b8220dd744eaf5ef9922e052e?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3df74477975a50f1c87a7dace91f34be8bb2637b8220dd744eaf5ef9922e052e?s=96&d=mm&r=g","caption":"Shavei Israel"},"url":"https:\/\/www.shavei.org\/es\/blog\/author\/shaveiisrael\/"}]}},"_links":{"self":[{"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/posts\/26353","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/comments?post=26353"}],"version-history":[{"count":1,"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/posts\/26353\/revisions"}],"predecessor-version":[{"id":26354,"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/posts\/26353\/revisions\/26354"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/media\/25290"}],"wp:attachment":[{"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/media?parent=26353"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/categories?post=26353"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.shavei.org\/es\/wp-json\/wp\/v2\/tags?post=26353"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}